{"id":13602,"date":"2026-07-15T11:07:06","date_gmt":"2026-07-15T09:07:06","guid":{"rendered":"https:\/\/meiser-tv.de\/news\/fresenius-ex-chef-wehrt-sich-gegen-gestrichene-bonuszahlungen-es-geht-um-millionen-a-4eace67a-0e4a-47c5-abc0-734eaa91497b\/"},"modified":"2026-07-15T11:07:06","modified_gmt":"2026-07-15T09:07:06","slug":"fresenius-ex-chef-wehrt-sich-gegen-gestrichene-bonuszahlungen-es-geht-um-millionen-a-4eace67a-0e4a-47c5-abc0-734eaa91497b","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/news\/fresenius-ex-chef-wehrt-sich-gegen-gestrichene-bonuszahlungen-es-geht-um-millionen-a-4eace67a-0e4a-47c5-abc0-734eaa91497b\/","title":{"rendered":"Fresenius: Ex-Chef wehrt sich gegen gestrichene Bonuszahlungen \u2013 es geht um Millionen"},"content":{"rendered":"<div>Der Gesundheitskonzern wirft seinem fr\u00fcheren Chef Pflichtverletzung vor und behielt seine Pr\u00e4mien ein. Sturm will das nicht hinnehmen \u2013 und bekommt dabei Unterst\u00fctzung von der Allianz.<\/div>","protected":false},"excerpt":{"rendered":"<div>Der Gesundheitskonzern wirft seinem fr\u00fcheren Chef Pflichtverletzung vor und behielt seine Pr\u00e4mien ein. Sturm will das nicht hinnehmen \u2013 und bekommt dabei Unterst\u00fctzung von der Allianz.<\/div>","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[18],"tags":[],"class_list":["post-13602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":[],"uagb_featured_image_src":{"full":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&resize=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&resize=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&resize=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Der Gesundheitskonzern wirft seinem fr\u00fcheren Chef Pflichtverletzung vor und behielt seine Pr\u00e4mien ein. Sturm will das nicht hinnehmen \u2013 und bekommt dabei Unterst\u00fctzung von der Allianz.","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=13602"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=13602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=13602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=13602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}