{"id":13633,"date":"2026-07-15T13:11:25","date_gmt":"2026-07-15T11:11:25","guid":{"rendered":"https:\/\/meiser-tv.de\/uncategorized\/im-schatten-der-wm\/"},"modified":"2026-07-15T13:11:25","modified_gmt":"2026-07-15T11:11:25","slug":"im-schatten-der-wm","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/uncategorized\/im-schatten-der-wm\/","title":{"rendered":"Im Schatten der WM"},"content":{"rendered":"<div>\n<h2 class=\"wp-block-heading\">Sportliche Gro\u00dfereignisse werden von Politikern gern dazu genutzt, um unbeliebte Vorhaben durchzusetzen \u2014 so geschehen auch bei der diesj\u00e4hrigen Fu\u00dfballweltmeisterschaft.<\/h2>\n<p class=\"wp-block-paragraph\">Ganz Fu\u00dfballdeutschland ist entt\u00e4uscht von Julian Nagelsmann und seinen Spielern. Zum ersten Mal seit 2014 kam die deutsche Mannschaft wieder \u00fcber die Qualifikationsphase hinaus, nur um dann im eigens f\u00fcr diese Weltmeisterschaft geschaffenen Sechzehntelfinale auszuscheiden. Doch w\u00e4hrend Nagelsmann nach seinem Misserfolg kurzerhand zur\u00fcckgetreten wurde, sind die politischen Entscheidungstr\u00e4ger in diesem Land trotz unterirdischer Zustimmungswerte flei\u00dfig dabei, Reformen durchzusetzen. Dabei d\u00fcrfte ihnen das fr\u00fche WM-Aus nicht gerade in die Karten spielen, denn sportliche Gro\u00dfveranstaltungen gerade im Bereich Fu\u00dfball binden die Aufmerksamkeit der breiten Bev\u00f6lkerung so effizient, dass ein gro\u00dfer Teil von ihr verpasst, darauf zu achten, was nebenbei noch so passiert. Die Zeit eignet sich also hervorragend f\u00fcr Ma\u00dfnahmen und Gesetze, die so unbeliebt sind, dass man sie ohne gro\u00dfen Wirbel \u00fcber den Tisch bringen will. Im angloamerikanischen Raum existiert hierf\u00fcr der Begriff \u201enews-dump\u201c, der die gezielte Bekanntgabe von schlechten Nachrichten zu Zeitpunkten, an denen sie m\u00f6glichst wenig Aufmerksamkeit erhalten, beschreibt. Auch die vergangenen Wochen waren hierf\u00fcr ein hervorragendes Beispiel.<\/p>\n<p class=\"wp-block-paragraph\">von Nicolas Riedl<\/p>\n<h2 class=\"wp-block-heading\">Reserveverst\u00e4rkungsgesetz<\/h2>\n<p class=\"wp-block-paragraph\">Gleich zu Beginn der Fu\u00dfball-Weltmeisterschaft kursierte eine Schockmeldung durch die freien, alternativen Medien, wonach ein \u201eImpfzwang durch die milit\u00e4rische Hintert\u00fcr\u201c drohe. Dies bezog<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Sportliche Gro\u00dfereignisse werden von Politikern gern dazu genutzt, um unbeliebte Vorhaben durchzusetzen \u2014 so geschehen auch bei der diesj\u00e4hrigen Fu\u00dfballweltmeisterschaft. Ganz Fu\u00dfballdeutschland ist entt\u00e4uscht von Julian Nagelsmann und seinen Spielern. Zum ersten Mal seit 2014 kam die deutsche Mannschaft wieder \u00fcber die Qualifikationsphase hinaus, nur um dann im eigens f\u00fcr diese Weltmeisterschaft geschaffenen Sechzehntelfinale auszuscheiden. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":[],"uagb_featured_image_src":{"full":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&resize=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&resize=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&resize=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Sportliche Gro\u00dfereignisse werden von Politikern gern dazu genutzt, um unbeliebte Vorhaben durchzusetzen \u2014 so geschehen auch bei der diesj\u00e4hrigen Fu\u00dfballweltmeisterschaft. Ganz Fu\u00dfballdeutschland ist entt\u00e4uscht von Julian Nagelsmann und seinen Spielern. Zum ersten Mal seit 2014 kam die deutsche Mannschaft wieder \u00fcber die Qualifikationsphase hinaus, nur um dann im eigens f\u00fcr diese Weltmeisterschaft geschaffenen Sechzehntelfinale auszuscheiden.&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=13633"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=13633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=13633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=13633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}