{"id":13688,"date":"2026-07-15T18:03:52","date_gmt":"2026-07-15T16:03:52","guid":{"rendered":"https:\/\/meiser-tv.de\/uncategorized\/hawaii-traegt-die-hauptlast-des-us-militaeraufbaus-gegen-china\/"},"modified":"2026-07-15T18:03:52","modified_gmt":"2026-07-15T16:03:52","slug":"hawaii-traegt-die-hauptlast-des-us-militaeraufbaus-gegen-china","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/uncategorized\/hawaii-traegt-die-hauptlast-des-us-militaeraufbaus-gegen-china\/","title":{"rendered":"Hawaii tr\u00e4gt die Hauptlast des US-Milit\u00e4raufbaus gegen China"},"content":{"rendered":"<div>\n<p class=\"wp-block-paragraph\">Hawaii fungiert als Dreh- und Angelpunkt eines riesigen pazifischen Netzwerks von St\u00fctzpunkten und \u00dcberwachungssystemen, doch das Auslaufen der Pachtvertr\u00e4ge f\u00fcr Milit\u00e4rst\u00fctzpunkte im Jahr 2029 bietet die M\u00f6glichkeit, das Land nachhaltiger zu nutzen.<br \/>Im Dezember 2025 ver\u00f6ffentlichte der hawaiianische Kongressabgeordnete Ed Case (D) eine Pressemitteilung , in der er seine Unterst\u00fctzung f\u00fcr den 900 Milliarden Dollar schweren National Defense Authorization Act (NDAA) bekannt gab, der 1 Milliarde Dollar f\u00fcr milit\u00e4rische Bauprojekte in Hawaii vorsah.<\/p>\n<p class=\"wp-block-paragraph\">Zu den Projekten geh\u00f6rten ein neues Trockendock f\u00fcr die Marinewerft Pearl Harbor, Modernisierungen der Schiffsunterst\u00fctzung auf der Pearl Harbor-Hickham-Basis, der Austausch des Haupttors auf der Marine Corps Base Hawai\u2019i und die Verbesserung des Flugfelds auf dem Gel\u00e4nde der Pacific Missile Range.<\/p>\n<p class=\"wp-block-paragraph\">Case hielt letztes Jahr vor dem Kongress eine Rede , in der er behauptete, der chinesische Staatschef Xi Jinping habe Republikaner, die gegen die Finanzierung des Ukraine-Krieges gestimmt hatten, bejubelt, weil sie angeblich Xis Ambitionen auf die Errichtung einer globalen chinesischen Vorherrschaft \u2013 erm\u00f6glicht durch eine isolationistische US-Politik \u2013 in die H\u00e4nde spielten.<\/p>\n<p class=\"wp-block-paragraph\">Cases Verwendung sinophober Rhetorik zur Rechtfertigung einer Ausweitung der US-Milit\u00e4rpr\u00e4senz in Hawaii findet ihr Gegenst\u00fcck in der anderen demokratischen Kongressabgeordneten Hawaiis, Jill Tokuda, die dem Sonderausschuss des Repr\u00e4sentantenhauses zur Kommunistischen Partei Chinas (KPCh) angeh\u00f6rt \u2013 einem Gremium, das Angst sch\u00fcrt und alarmistische Rhetorik sowie falsche Anschuldigungen gegen China verbreitet, die an die McCarthy-\u00c4ra erinnern. [1]<\/p>\n<p class=\"wp-block-paragraph\">Ende Mai ver\u00f6ffentlichte das Institute for Policy Studies einen\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/ips-dc.org\/wp-content\/uploads\/2026\/05\/report_true_cost_of_us_military_in_hawaii.pdf\">Bericht<\/a>\u00a0\u2013 der in Zusammenarbeit mit zwei Menschenrechts-NGOs (\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.ainaalohafutures.com\/\">\u0100ina Aloha Economic Futures<\/a>\u00a0und\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.facebook.com\/Ilioulaokalani\/\">\u012alio\u02bbulaokalani Coalition),<\/a>\u00a0dem\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/sierraclubhawaii.org\/\">Hawai\u2019i Sierra Club<\/a>\u00a0und\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/costsofwar.watson.brown.edu\/\">dem Cost of War Project<\/a>\u00a0der Brown University erstellt wurde \u2013, der die ersch\u00fctternden Kosten der US-Milit\u00e4rpr\u00e4senz in Hawai\u2019i aufzeigt, die sich aufgrund des neuen Kalten Krieges noch versch\u00e4rfen.<\/p>\n<p class=\"wp-block-paragraph\">Der Bericht mit dem Titel\u00a0<em>\u201eDie wahren Kosten des US-Milit\u00e4rs in Hawai\u2019i\u201c<\/em>\u00a0verdeutlicht Hawai\u2019is Funktion als \u201ezentraler Knotenpunkt\u201c in der US-Kriegsplanung im Indopazifik, die bis zum illegalen Sturz von K\u00f6nigin Lili\u2019uokalani und des K\u00f6nigreichs Hawaii durch US-Marines im Jahr 1893 zur\u00fcckreicht.<\/p>\n<p class=\"wp-block-paragraph\">Pr\u00e4sident Grover Cleveland bezeichnete den US-amerikanischen Putsch auf Hawaii im Jahr 1893 als \u201eeinen Kriegsakt, der ohne die Befugnis des Kongresses begangen wurde\u201c.<\/p>\n<p class=\"wp-block-paragraph\">Im Jahr 1899 wurde Hawai\u2019i zur Betankung von Marineschiffen genutzt, als die USA die Philippinen kolonisierten, und 1929 begann die US-Armee, Grundst\u00fccke zu erwerben, die f\u00fcr milit\u00e4rische \u00dcbungen genutzt wurden.<\/p>\n<p class=\"wp-block-paragraph\">Nach den Angriffen auf Pearl Harbor wurde in Hawai\u2019i f\u00fcr die n\u00e4chsten drei Jahre das Kriegsrecht verh\u00e4ngt, und die US-Armee vertrieb alle Einwohner von M\u0101kua, um deren Land f\u00fcr \u00dcbungszwecke zu beschlagnahmen.\u00a0<br \/><sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-2\">[2]<\/a><\/sup><\/p>\n<p class=\"wp-block-paragraph\">Im Januar 1976 besetzte eine Koalition von Aktivisten, teilweise inspiriert von den Besetzungen von Alcatraz und Wounded Knee durch die Ureinwohner Amerikas, Kaho\u02bbolawe, eine Insel, auf der Bombenangriffe und \u00dcbungen durchgef\u00fchrt wurden und die Truppen vor ihrem Einsatz im Korea- und Vietnamkrieg durchquerten.<\/p>\n<p class=\"wp-block-paragraph\">Das Schie\u00dftraining wurde dort 1990 eingestellt, und seitdem wurden Gelder investiert, um Blindg\u00e4nger zu beseitigen, die gro\u00dfe Teile der\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/kawaiola.news\/oha\/trustees\/kahoolawe-a-sacred-islands-journey\/\">heiligen Insel unsicher<\/a>\u00a0gemacht hatten .<\/p>\n<p class=\"wp-block-paragraph\">Die Ausweitung der milit\u00e4rischen Ausbildungsoperationen im letzten Jahrzehnt erfolgte im Rahmen der von der Obama-Regierung initiierten \u201eHinwendung zu Asien\u201c und der Planung f\u00fcr einen neuen Pazifikkrieg.\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-3\">[3]<\/a><\/sup><\/p>\n<p class=\"wp-block-paragraph\">Stabsfeldwebel Kevin Cassara wurde\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/monocle.com\/affairs\/defence\/us-military-training-hawaii\/\">in\u00a0<em>Monocle<\/em><\/a>\u00a0, einem Magazin f\u00fcr internationale Angelegenheiten, mit den Worten zitiert: \u201eDas Marine Corps kehrt zu seinen amphibischen Wurzeln zur\u00fcck. Wir wandeln uns zu einer leichten Infanterietruppe, die auf Inseln operieren kann \u2013 und Hawaii ist daf\u00fcr unerl\u00e4sslich. Wir k\u00f6nnen dort die Bedingungen simulieren, denen sie im S\u00fcdchinesischen Meer begegnen werden.\u201c<\/p>\n<p class=\"wp-block-paragraph\">Das US-Milit\u00e4r hat derzeit mehr als 107.000 Soldaten in Hawaii stationiert und kontrolliert sch\u00e4tzungsweise 133 Standorte mit einer Gesamtfl\u00e4che von 254.225 Acres, zuz\u00fcglich weiterer 1.017 Acres, die von der Hawaii Nationalgarde betrieben werden.<\/p>\n<p class=\"wp-block-paragraph\">Das 1947 gegr\u00fcndete Indo-Pazifik-Kommando (USINDOPACOM) ist das \u00e4lteste und gr\u00f6\u00dfte gemeinsame Kommando der USA und hat seinen Hauptsitz in Camp Smith mit Blick auf Pearl Harbor.<\/p>\n<p class=\"wp-block-paragraph\">Die US Pacific Fleet (PACFLT) mit Hauptsitz auf der Joint Base Pearl Harbor-Hickam (JBPHH) ist das gr\u00f6\u00dfte Marinekommando der Welt und verantwortlich f\u00fcr kilometerlange Ozeane, fast 200 Schiffe, 1.700 Flugzeuge und mehr als 225.000 Matrosen und Marinesoldaten.<\/p>\n<ol class=\"wp-block-list\">\n<li>die Air Force Maui Optical and Supercomputing Site auf Haleakal\u0101;<\/li>\n<li>die Weltraumstreitkr\u00e4ftestation Ka\u2019ena Point auf O\u2019ahu;<\/li>\n<li>Marine-Ortungseinrichtungen im Zusammenhang mit der Pacific Missile Range Facility (PMRF) auf Kaua\u2019I;<\/li>\n<li>eine zentrale Marine-Computer- und Telekommunikationsstation (NCTAMS); und<\/li>\n<li>ein regionales Fernmeldeaufkl\u00e4rungszentrum der National Security Agency\/Central Security Service (NSA\/CSS), in dem Edward Snowden arbeitete.\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-4\">[4]<\/a><\/sup><\/li>\n<\/ol>\n<p class=\"wp-block-paragraph\">Zu den weiteren wichtigen milit\u00e4rischen\/nachrichtendienstlichen Einrichtungen geh\u00f6ren:Kyle Kajihiro\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-5\">[5]<\/a><\/sup>\u00a0und Neta Crawford\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-6\">[6]<\/a><\/sup>\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/kawaiola.news\/aina\/what-is-driving-the-military-expansion-in-hawaii\/\">berichteten<\/a>\u00a0im Januar, dass die US Navy eine Erh\u00f6hung der Bombardierungen von Ka\u2019ula (einer Insel und einem Seevogelschutzgebiet vor Ni\u2019ihau), eine Erh\u00f6hung der \u00dcbungen auf See um Hawai\u2019i und Kalifornien, eine Erh\u00f6hung des Einsatzes von Unterwassersprengstoffen und eine h\u00f6here genehmigte Entnahme von Meeresarten vorgeschlagen habe.<\/p>\n<p class=\"wp-block-paragraph\">Die US-Armee hat ihre Ausbildung mit anderen L\u00e4ndern in Hawaii durch das Joint Pacific Multinational Readiness Center weiter ausgebaut.<\/p>\n<p class=\"wp-block-paragraph\">Diese Initiativen werden die bereits verheerenden Folgen der US-Milit\u00e4rpr\u00e4senz in Hawaii, die in \u201e\u00a0<em>The True Cost of the US Military in Hawaii\u201c dokumentiert sind,<\/em>\u00a0nur noch verschlimmern . In dem Buch wird gesch\u00e4tzt, dass das Pentagon Hawaii zwischen 32,8 Milliarden und 133,7 Milliarden Dollar an unbezahlter Miete schuldet.<\/p>\n<p class=\"wp-block-paragraph\">Seit 1964 pachtet das US-Milit\u00e4r zehntausende Hektar \u00f6ffentliches Treuhandland in Hawaii f\u00fcr eine symbolische Geb\u00fchr von 1 Dollar pro Jahr.<\/p>\n<p class=\"wp-block-paragraph\">Die obige Sch\u00e4tzung beinhaltet nicht die zus\u00e4tzlichen Kosten in Milliardenh\u00f6he f\u00fcr die Beseitigung von Umweltsch\u00e4den, die durch das US-Milit\u00e4r verursacht wurden, sowie f\u00fcr die Zerst\u00f6rung von Kultur- und arch\u00e4ologischen St\u00e4tten.<\/p>\n<p class=\"wp-block-paragraph\">Zu den Umweltsch\u00e4den z\u00e4hlen gro\u00dfe Waldbr\u00e4nde, die durch Munitionstests auf dem P\u014dhakuloa-\u00dcbungsgel\u00e4nde und anderswo ausgel\u00f6st wurden, sowie die Kontamination von Hawaiis Boden und Trinkwasser mit per- und polyfluorierten Alkylsubstanzen (PFAS), die aus verschiedenen Waffensystemen stammen und mit Sch\u00e4den bei F\u00f6ten und Krebs in Verbindung gebracht werden.<\/p>\n<p class=\"wp-block-paragraph\">Im November 2021 bemerkten Tausende von Anwohnern in der N\u00e4he von Pearl Harbor, dass ihr Leitungswasser nach Treibstoff roch, und berichteten von Kopfschmerzen, \u00dcbelkeit, Erbrechen und Hautausschl\u00e4gen.<\/p>\n<p class=\"wp-block-paragraph\">Innerhalb weniger Wochen stellten die Ermittler fest, dass die Red Hill Bulk Fuel Storage Facility der US-Marine \u2013 in der rund 250 Millionen Gallonen Kerosin nur 100 Fu\u00df \u00fcber dem Hauptgrundwasserleiter von O\u2019ahu gelagert wurden \u2013 ein Leck aufwies und die Trinkwasserversorgung von 93.000 Menschen verunreinigte.<\/p>\n<p class=\"wp-block-paragraph\">Nach dem Bekanntwerden des Lecks bezeichnete Gouverneur David Ige das Milit\u00e4r als einen \u201edynamischen Teil unserer Wirtschaft\u201c, um seine Zur\u00fcckhaltung bei der Anordnung der Schlie\u00dfung des unterirdischen Treibstofflagers Red Hill zu rechtfertigen.<\/p>\n<p class=\"wp-block-paragraph\"><em>Der Bericht \u201eDie wahren Kosten des US-Milit\u00e4rs in Hawaii\u201c<\/em>\u00a0zeigt jedoch, dass die angeblichen wirtschaftlichen Vorteile des US-Milit\u00e4rs in Hawaii grob \u00fcbersch\u00e4tzt wurden und gr\u00f6\u00dftenteils negativ sind, da das Milit\u00e4r begehrtes Land besetzt und die Schaffung von Arbeitspl\u00e4tzen in anderen gesellschaftlichen Sektoren behindert.<\/p>\n<p class=\"wp-block-paragraph\">In einem Kapitel mit dem Titel \u201eDie wahren wirtschaftlichen Auswirkungen des US-Milit\u00e4rs in Hawaii\u201c stellt der Anthropologe David Vine fest, dass die wirtschaftlichen Auswirkungen der Milit\u00e4rausgaben fast 30 % geringer sind als behauptet und dass der Anteil des Milit\u00e4rs am hawaiianischen BIP geringer ist als der Anteil der Immobilien-, Beherbergungs- und Gastronomiebranche.<\/p>\n<p class=\"wp-block-paragraph\">Omar Ocampo\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-7\">[7]<\/a><\/sup>\u00a0und Brag Selvarajan\u00a0 <sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-8\">[8]<\/a><\/sup>\u00a0zeigen in ihrem Kapitel, dass die Nachfrage nach Milit\u00e4rwohnungen in Hawai\u2019i im Jahr 2024 zu einem Anstieg der Mieten um 7,1 % f\u00fchrte, wodurch nicht-milit\u00e4rische Mieter in Hawai\u2019i in diesem Jahr sch\u00e4tzungsweise 234,8 Millionen Dollar mehr an Miete ausgeben mussten, was 1.848 Dollar pro Mieterhaushalt entspricht.<\/p>\n<p class=\"wp-block-paragraph\">Vine argumentiert, dass ein Teil des Problems darin bestehe, dass viele Milit\u00e4rauftr\u00e4ge an gro\u00dfe Konzerne mit Hauptsitz au\u00dferhalb von Hawaii vergeben w\u00fcrden, die keine lokalen Steuern zahlten.\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-9\">[9]<\/a><\/sup><\/p>\n<p class=\"wp-block-paragraph\">Da es sich um Bundesgrundst\u00fccke handelt, unterliegen Milit\u00e4rst\u00fctzpunkte auch nicht der Grundsteuer.<\/p>\n<p class=\"wp-block-paragraph\">Hinzu kommt, dass viele Milit\u00e4rangeh\u00f6rige nur vor\u00fcbergehend auf dem St\u00fctzpunkt oder auf Marineschiffen wohnen und daher keine lokalen Steuern zahlen oder nennenswert in die lokale Wirtschaft investieren.<\/p>\n<p class=\"wp-block-paragraph\">Im Allgemeinen schaffen Milit\u00e4rausgaben weniger Arbeitspl\u00e4tze als Investitionen in Sektoren wie Gesundheitswesen, Bildung, Wohnungsbau, Nahrungsmittelproduktion oder energieeffiziente Wohnungsmodernisierungen.\u00a0<sup><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-10\">[10]<\/a><\/sup><\/p>\n<p class=\"wp-block-paragraph\">Heidi Peltier, Forscherin an der Watson School of International and Public der Brown University<\/p>\n<p class=\"wp-block-paragraph\">Das Ministerium f\u00fcr Angelegenheiten sch\u00e4tzt, dass f\u00fcr jede Million Dollar, die von Milit\u00e4rausgaben in Bildung oder Gesundheitswesen in Hawaii umgeleitet wird, f\u00fcnf Arbeitspl\u00e4tze verloren gehen w\u00fcrden, aber zwischen 10 und 22 Arbeitspl\u00e4tze geschaffen w\u00fcrden, was einen Nettogewinn von 5 bis 17 Arbeitspl\u00e4tzen erg\u00e4be.\u00a0<\/p>\n<p class=\"wp-block-paragraph\">Am Ende des Berichts betonen die Autoren, dass das Auslaufen der Milit\u00e4rlandpachtvertr\u00e4ge im Jahr 2029 eine Chance bietet, die St\u00fctzpunkte in neue, nicht-milit\u00e4rische Nutzungen umzuwandeln, die den lokalen Gemeinschaften zugutekommen, beispielsweise durch die Einrichtung von Schulen, Krankenh\u00e4usern, Parks, landwirtschaftlichen Betrieben, Kulturst\u00e4tten, Gr\u00fcnderzentren, Unterhaltungszentren und Projekten f\u00fcr erneuerbare Energien.<\/p>\n<p class=\"wp-block-paragraph\">Das Pentagon wird nat\u00fcrlich alles daransetzen, dies zu verhindern, indem es mit angstsch\u00fcrender antichinesischer Rhetorik und \u00fcbertriebenen Behauptungen \u00fcber den wirtschaftlichen Nutzen des Milit\u00e4rs versucht, die fortgesetzte Besetzung hawaiianischen Territoriums zu rechtfertigen. Die Oppositionsbewegung in Hawaii ist jedoch erstarkt und hat die Gerechtigkeit auf ihrer Seite.<\/p>\n<p class=\"wp-block-paragraph\">Anmerkungen:<\/p>\n<p>Case\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.opensecrets.org\/profiles\/ed-case\/us_congress\/summary?mpid=1047537\">erhielt 2025\/26 \u00fcber 12.000 US-Dollar<\/a>\u00a0an Wahlkampfspenden von Anduril, einem f\u00fchrenden Drohnenhersteller. Tokuda erhielt\u00a02025\/26\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.opensecrets.org\/profiles\/n00051049\/us_congress\/summary?mpid=1176532\">19.000 US-Dollar an Wahlkampfspenden von\u00a0<\/a><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/e-o.solutions\/\">EO Solutions<\/a>\u00a0, einem auf KI-Anwendungen und Hochenergiewaffen spezialisierten R\u00fcstungsunternehmen.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-1\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Das Milit\u00e4rgel\u00e4nde M\u0101kua umfasst mittlerweile mehr als 4.000 Acres.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-2\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Mehr zur Bedeutung des \u201ePivot to Asia\u201c der Obama-Regierung finden Sie in Jeremy Kuzmarov,\u00a0<em>Obama\u2019s Unending Wars: Fronting the Foreign Policy of the Permanent Warfare State<\/em>\u00a0(Atlanta: Clarity Press, 2019).\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-3\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Unterwasser-Akustiksensoren im Ozean nahe PMRF \u00fcberwachen Marine\u00fcbungen. Das regionale Fernmeldeaufkl\u00e4rungszentrum der NSA\/CSS ist laut dem Bericht \u201e\u00a0<em>Die wahren Kosten des US-Milit\u00e4rs in Hawaii\u201c in inl\u00e4ndische \u00dcberwachungsprogramme verwickelt.\u00a0<\/em><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-4\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Kajihiro ist Professor f\u00fcr Ethnische Studien an der Universit\u00e4t von Hawai\u2019i.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-5\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Crawford ist Professor f\u00fcr Internationale Beziehungen an der Universit\u00e4t St. Andrews in Schottland und Mitbegr\u00fcnder und strategischer Berater des Projekts \u201eKosten des Krieges\u201c der Brown University.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-6\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Omar Ocampo ist Forscher im Programm f\u00fcr Ungleichheit und Gemeinwohl am Institut f\u00fcr Politikstudien.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-7\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Brag Selvarajan ist unabh\u00e4ngiger Berater bei Selvara Strategy.\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-8\">\u2191<\/a><\/p>\n<p class=\"wp-block-paragraph\">Der Bericht listet einige der gr\u00f6\u00dften Empf\u00e4nger von Pentagon-Auftr\u00e4gen in Hawaii nach Dollarwert auf: a) Nan, Inc., ein Bauunternehmen, das Junggesellenunterk\u00fcnfte auf einem Marinest\u00fctzpunkt errichtete; b) Hensel Phelps, ein Bauunternehmen, das Verwaltungsgeb\u00e4ude reparierte; c) Koa Lani, das Betriebsunterst\u00fctzung f\u00fcr eine Raketentestanlage leistet; d) BAE Systems, das Schiffbau und -reparaturen durchf\u00fchrt; und e) IES Downstream, das die Treibstoffversorgung f\u00fcr Anlagen \u00fcbernimmt.<\/p>\n<p class=\"wp-block-paragraph\">Zu den parasit\u00e4ren Auswirkungen milit\u00e4rbezogener Ausgaben siehe Seymour Melmans Standardwerk \u201e\u00a0<em>Pentagon Capitalism: The Political Economy of War\u201c<\/em>\u00a0(New York: McGraw-Hill, 1970).\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/covertactionmagazine.com\/2026\/07\/07\/hawaii-bearing-huge-brunt-of-u-s-military-buildup-directed-against-china\/?utm_source=substack&amp;utm_medium=email#post-91983-footnote-ref-10\">\u2191<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hawaii fungiert als Dreh- und Angelpunkt eines riesigen pazifischen Netzwerks von St\u00fctzpunkten und \u00dcberwachungssystemen, doch das Auslaufen der Pachtvertr\u00e4ge f\u00fcr Milit\u00e4rst\u00fctzpunkte im Jahr 2029 bietet die M\u00f6glichkeit, das Land nachhaltiger zu nutzen.Im Dezember 2025 ver\u00f6ffentlichte der hawaiianische Kongressabgeordnete Ed Case (D) eine Pressemitteilung , in der er seine Unterst\u00fctzung f\u00fcr den 900 Milliarden Dollar schweren [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":[],"uagb_featured_image_src":{"full":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&resize=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&resize=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&resize=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Hawaii fungiert als Dreh- und Angelpunkt eines riesigen pazifischen Netzwerks von St\u00fctzpunkten und \u00dcberwachungssystemen, doch das Auslaufen der Pachtvertr\u00e4ge f\u00fcr Milit\u00e4rst\u00fctzpunkte im Jahr 2029 bietet die M\u00f6glichkeit, das Land nachhaltiger zu nutzen.Im Dezember 2025 ver\u00f6ffentlichte der hawaiianische Kongressabgeordnete Ed Case (D) eine Pressemitteilung , in der er seine Unterst\u00fctzung f\u00fcr den 900 Milliarden Dollar schweren&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=13688"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=13688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=13688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=13688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}