{"id":13696,"date":"2026-07-15T19:06:59","date_gmt":"2026-07-15T17:06:59","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/eu-gelder-fuer-ukraine-kiew-darf-chinesische-drohnen-teile-kaufen\/"},"modified":"2026-07-15T19:06:59","modified_gmt":"2026-07-15T17:06:59","slug":"eu-gelder-fuer-ukraine-kiew-darf-chinesische-drohnen-teile-kaufen","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/eu-gelder-fuer-ukraine-kiew-darf-chinesische-drohnen-teile-kaufen\/","title":{"rendered":"EU-Gelder f\u00fcr Ukraine: Kiew darf chinesische Drohnen-Teile kaufen"},"content":{"rendered":"<div>\n<p data-start=\"32\" data-end=\"305\">Die Ukraine darf Mittel aus einem EU-Verteidigungskredit f\u00fcr den Kauf chinesischer Drohnen-Komponenten verwenden. Dies mache Europas Abh\u00e4ngigkeit von Peking bei wichtigen Bauteilen deutlich, w\u00e4hrend die EU Schwierigkeiten habe, eine eigene Verteidigungsindustrie aufzubauen, kommentierte die\u00a0<em>Financial Times<\/em> am Mittwoch.<\/p>\n<p data-start=\"307\" data-end=\"691\">Kiew hat nach Angaben von zwei mit der Entscheidung vertrauten Personen eine Ausnahmegenehmigung f\u00fcr einen Teil einer 6-Milliarden-Euro-Tranche erhalten, um Drohnen-Komponenten aus China zu kaufen. Die Mittel sind die erste Auszahlung aus einem gr\u00f6\u00dferen Unterst\u00fctzungskredit f\u00fcr die Ukraine, aus dem insgesamt 60 Milliarden Euro f\u00fcr Verteidigungsbeschaffungen vorgesehen sind.<\/p>\n<p data-start=\"693\" data-end=\"959\" data-is-last-node=\"\" data-is-only-node=\"\">Die Entscheidung verdeutlicht die weiterhin bestehenden L\u00fccken in der europ\u00e4ischen Verteidigungsproduktion \u2013 trotz der Bem\u00fchungen der EU, Europas industrielle Basis zu st\u00e4rken, indem Hilfen f\u00fcr die Ukraine an die Beschaffung\u00a0auf dem Kontinent gekn\u00fcpft werden:\u00a0Nach den Bedingungen des EU-Kredits m\u00fcssen Verteidigungsprodukte, die mit Mitteln des Blocks gekauft werden, gr\u00f6\u00dftenteils aus dem EU-Binnenmarkt, aus der Ukraine oder von zugelassenen Partnern wie Kanada stammen.<\/p>\n<p data-start=\"1447\" data-end=\"1696\">Auch andere Verb\u00fcndete k\u00f6nnen zugelassen werden, wenn sie eine Sicherheitspartnerschaft mit der EU unterzeichnen, sich an dem Programm beteiligen und umfangreiche Unterst\u00fctzung f\u00fcr die Ukraine leisten. Gro\u00dfbritannien trat dem Programm am Montag bei.<\/p>\n<p data-start=\"1698\" data-end=\"1971\">Bei Lieferanten au\u00dferhalb dieser zugelassenen Kategorien d\u00fcrfen h\u00f6chstens 35 Prozent eines Vertrags aus Komponenten anderer L\u00e4nder bestehen. Die Regelung sieht vor, dass R\u00fcstungsk\u00e4ufe nicht den &#8222;Sicherheits- und Verteidigungsinteressen&#8220; der EU widersprechen d\u00fcrfen.<\/p>\n<p data-start=\"1973\" data-end=\"2253\">Die Regeln enthalten jedoch auch eine Ausnahme. Wenn vergleichbare Produkte nicht schnell genug oder nicht in den von der Ukraine ben\u00f6tigten Mengen aus zugelassenen L\u00e4ndern beschafft werden k\u00f6nnen, kann Kiew bei Br\u00fcssel eine Genehmigung beantragen, sie anderswo zu erwerben.<\/p>\n<p data-start=\"2255\" data-end=\"2600\">Die Ukraine beantragte und erhielt eine Ausnahme f\u00fcr die erste, 5,9 Milliarden Euro schwere Verteidigungs-Tranche, die speziell f\u00fcr die Beschaffung von Drohnen vorgesehen ist. Dadurch k\u00f6nne Kiew bestimmte chinesische Komponenten erwerben, die in Europa nicht ausreichend verf\u00fcgbar seien, erkl\u00e4rten die mit der Entscheidung vertrauten Personen gegen\u00fcber <em>FT<\/em>.<\/p>\n<p data-start=\"2602\" data-end=\"2721\" data-is-last-node=\"\" data-is-only-node=\"\">Die Europ\u00e4ische Kommission und das ukrainische Verteidigungsministerium reagierten nicht auf\u00a0Bitten um Stellungnahme.<\/p>\n<p data-start=\"2602\" data-end=\"2721\" data-is-last-node=\"\" data-is-only-node=\"\"><strong>Mehr zum Thema<\/strong> &#8211; <a href=\"https:\/\/freedert.online\/meinung\/285756-kiews-vorschlag-mit-dank-angenommen-russland-entscheidet-krieg-jetzt-luft\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kiews Vorschlag mit Dank angenommen \u2013 Russland entscheidet den Krieg jetzt in der Luft<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7aj72w\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Ukraine darf Mittel aus einem EU-Verteidigungskredit f\u00fcr den Kauf chinesischer Drohnen-Komponenten verwenden. Dies mache Europas Abh\u00e4ngigkeit von Peking bei wichtigen Bauteilen deutlich, w\u00e4hrend die EU Schwierigkeiten habe, eine eigene Verteidigungsindustrie aufzubauen, kommentierte die\u00a0Financial Times am Mittwoch. Kiew hat nach Angaben von zwei mit der Entscheidung vertrauten Personen eine Ausnahmegenehmigung f\u00fcr einen Teil einer 6-Milliarden-Euro-Tranche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-13696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":[],"uagb_featured_image_src":{"full":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&resize=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&resize=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&resize=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&resize=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&resize=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/i3.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&resize=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Die Ukraine darf Mittel aus einem EU-Verteidigungskredit f\u00fcr den Kauf chinesischer Drohnen-Komponenten verwenden. Dies mache Europas Abh\u00e4ngigkeit von Peking bei wichtigen Bauteilen deutlich, w\u00e4hrend die EU Schwierigkeiten habe, eine eigene Verteidigungsindustrie aufzubauen, kommentierte die\u00a0Financial Times am Mittwoch. Kiew hat nach Angaben von zwei mit der Entscheidung vertrauten Personen eine Ausnahmegenehmigung f\u00fcr einen Teil einer 6-Milliarden-Euro-Tranche&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=13696"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/13696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=13696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=13696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=13696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}