{"id":20138,"date":"2026-08-31T07:02:03","date_gmt":"2026-08-31T05:02:03","guid":{"rendered":"https:\/\/meiser-tv.de\/wirtschaft\/chemie-stahl-maschinenbau-da-zuckt-noch-was-38179886-html\/"},"modified":"2026-08-31T07:02:03","modified_gmt":"2026-08-31T05:02:03","slug":"chemie-stahl-maschinenbau-da-zuckt-noch-was-38179886-html","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/wirtschaft\/chemie-stahl-maschinenbau-da-zuckt-noch-was-38179886-html\/","title":{"rendered":"Kolumne: Chemie, Stahl, Maschinenbau &#8211; da zuckt noch was"},"content":{"rendered":"<div>\n<div>\n<div class=\"rtf-content-wrapper\">\n<p>Selbst die Problemkinder der deutschen Industrie schlagen sich besser als erwartet. Doch noch ist die Krise nicht \u00fcberwunden<\/p>\n<\/div>\n<div class=\"rtf-content-wrapper\">\n<p class=\"align--justify\">Nun also endlich auch die Chemiebranche: Zum ersten Mal seit vier Jahren melden die Manager von BASF, Evonik, Lanxess und Co. wieder eine positive Entwicklung ihres Gesch\u00e4fts, wie eine Umfrage des Ifo-Instituts aus der letzten Woche zeigt. Das sogenannte Gesch\u00e4ftsbarometer stieg im August auf einen Schlag von minus 14,6 Punkten auf plus 11,6 Punkte. Und auch in die Zukunft blickt die Chemieindustrie wieder hoffnungsvoller.<\/p>\n<p class=\"align--justify\">\n<p class=\"align--justify\">Die Chemie verzeichnet als letzte der drei gro\u00dfen Krisenbranchen eine Trendwende. Zuvor signalisierte bereits der deutsche Maschinenbau erste Anzeichen f\u00fcr eine Wende zum Besseren. Zwar fielen die Ums\u00e4tze der Branche im ersten Halbjahr noch, aber zuletzt verzeichnete man ein kr\u00e4ftiges Exportplus von 6,8 Prozent und eine allgemeine Stabilisierung an der Auftragsfront. Selbst das Problemkind Nummer Eins der deutschen Industrie, die Stahlbranche, zeigt inzwischen deutliche Spuren eines kleinen Aufschwungs nach langer Talfahrt.\u00a0<\/p>\n<p class=\"align--justify\">Der gr\u00f6\u00dfte Stahlhersteller Thyssenkrupp Steel Europe (TKSE) verbuchte in den ersten neun Monaten des laufenden Gesch\u00e4ftsjahrs zwar noch ein Umsatzminus von drei Prozent, konnte jedoch deutlich h\u00f6here Mengen absetzen (plus 9 Prozent im Vergleich zum Vorjahreszeitraum). Die operative Marge \u00a0von TKSE stieg von 2,4 auf 5,3 Prozent.<\/p>\n<h2>Die Entwicklung h\u00e4ngt an den USA und China<\/h2>\n<p class=\"align--justify\">N\u00e4hern wir uns dem Anfang vom Ende der Krise in den drei Schl\u00fcsselindustrien? Die Antwort lautet: Jein. Die Chemie f\u00fchrt ihre positive Entwicklung auf \u201eSonderfaktoren\u201c zur\u00fcck: Sie profitiert von den Problemen der Konkurrenz in Asien, ausgel\u00f6st durch die Lieferausf\u00e4lle nach der Blockade der Stra\u00dfe von Hormus. Unter \u201egeopolitischen Spannungen\u201c leiden auch die deutschen Maschinenbauer, wie ihr Verband betont. Und in der Stahlindustrie gibt es so viele Unsicherheitsfaktoren, dass sich kaum jemand eine l\u00e4ngerfristige Positivprognose zutraut.<\/p>\n<\/p>\n<p class=\"align--justify\">F\u00fcr alle drei Krisenbranchen gilt bei allen Unterschieden: Ihr Schicksal entscheidet sich in den USA und China. Beide M\u00e4rkte belasten die Ergebnisse der Chemie, des Stahls und des Maschinenbaus weiter direkt und indirekt. Donald Trump sorgt mit seiner unberechenbaren Zollpolitik immer wieder f\u00fcr heftige Ausschl\u00e4ge in der deutschen Exportstatistik. Und in der Volksrepublik China sind es vor allem die schw\u00e4chelnde Binnennachfrage und die aggressive Dumpingstrategie der dortigen Konzerne, die deutschen Konkurrenten das Leben schwer machen. Oft sp\u00fcrt man die Auswirkungen der Gemengelage gar nicht so sehr direkt in Deutschland, sondern auf Drittm\u00e4rkten. Das macht Antworten noch komplizierter.<\/p>\n<p class=\"align--justify\">Die drei Krisenbranchen geh\u00f6rten in den vergangenen Jahren zu den lautst\u00e4rksten Kritikern des Standorts Deutschland. Durch ihre anhaltenden Wehklagen verst\u00e4rkten sie den deutschen Hang, die heimische Wirtschaftsentwicklung grau in grau zu malen.\u00a0<\/p>\n<p class=\"align--justify\">Vielleicht w\u00e4re es auch f\u00fcr die Lautsprecher der Branche an der Zeit, ihre Analysen etwas differenzierter in die \u00d6ffentlichkeit zu tragen als bisher. Denn zu den Voraussetzungen f\u00fcr einen richtigen Aufschwung geh\u00f6rt nun einmal auch ein bisschen Zweckoptimismus.\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<div>Selbst die Problemkinder der deutschen Industrie schlagen sich besser als erwartet. Doch noch ist die Krise nicht \u00fcberwunden<\/div>","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-20138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Selbst die Problemkinder der deutschen Industrie schlagen sich besser als erwartet. Doch noch ist die Krise nicht \u00fcberwunden","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20138"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}