{"id":20141,"date":"2026-08-31T07:03:13","date_gmt":"2026-08-31T05:03:13","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/warum-der-august-1991-keinen-frieden-zwischen-russland-und-dem-westen-brachte\/"},"modified":"2026-08-31T07:03:13","modified_gmt":"2026-08-31T05:03:13","slug":"warum-der-august-1991-keinen-frieden-zwischen-russland-und-dem-westen-brachte","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/warum-der-august-1991-keinen-frieden-zwischen-russland-und-dem-westen-brachte\/","title":{"rendered":"Warum der August 1991 keinen Frieden zwischen Russland und dem Westen brachte"},"content":{"rendered":"<div>\n<p><em>Von Timofei Bordatschow<\/em><\/p>\n<p><strong><\/strong><em><\/em>Seit den dramatischen Ereignissen vom August 1991 in Moskau sind nun 35 Jahre vergangen. Sie markierten deutlicher als alle nachfolgenden Deklarationen und diplomatischen Zeremonien das Ende jener Epoche, die wir als &#8222;Kalten Krieg&#8220; bezeichnen.<\/p>\n<p>Der gescheiterte Versuch des &#8222;Augustputsches&#8220;, der auf den Erhalt der Sowjetunion abzielte, machte eine Fortsetzung der bisherigen Konfrontation unm\u00f6glich: Einer ihrer wichtigsten Akteure hatte das &#8222;Spielfeld&#8220; faktisch verlassen. Alles, was darauf folgte, einschlie\u00dflich des offiziellen Zerfalls der UdSSR im Dezember 1991, best\u00e4tigte lediglich eine Ver\u00e4nderung, die bereits eingetreten war.<\/p>\n<p>Entscheidend war, dass die Sowjetunion und sp\u00e4ter auch Russland nicht mehr in der Lage waren, die materiellen und politischen Grundlagen aufrechtzuerhalten, die f\u00fcr die Fortsetzung des Konflikts erforderlich waren. Daf\u00fcr gab es viele Gr\u00fcnde, doch der wichtigste war die Ersch\u00f6pfung des sowjetischen Staatsmodells.<\/p>\n<p>Daher beschloss Moskau, die Konfrontation zu beenden. Dies war historisch gesehen ungew\u00f6hnlich: Russland war weder auf dem Schlachtfeld besiegt noch zur Kapitulation gezwungen worden. Der Kalte Krieg endete vielmehr infolge innenpolitischer Ver\u00e4nderungen und einer freiwilligen Entscheidung der sowjetischen F\u00fchrung.<\/p>\n<p>So paradox es auch klingen mag: Ein solch friedlicher Ausgang erh\u00f6hte die Wahrscheinlichkeit einer k\u00fcnftigen Konfrontation. Der Hauptgrund war einfach: Die westlichen M\u00e4chte unter F\u00fchrung der USA betrachteten das Ende des Kalten Krieges als ihren Sieg, Russland hingegen sah sich selbst nicht als besiegtes Land. Dieser Widerspruch wurde zu einem der zentralen Probleme der Weltordnung nach dem Kalten Krieg.<\/p>\n<p>Gro\u00dfe Atomm\u00e4chte wie Russland, die USA und China lassen sich milit\u00e4risch kaum besiegen, ohne die gegenseitige Vernichtung zu riskieren. Die gr\u00f6\u00dften Gefahren f\u00fcr solche Staaten entstehen daher in der Regel im Inneren \u2013 durch politische Fehlentwicklungen, wirtschaftliche Schw\u00e4che, mangelnde Regierungsf\u00e4higkeit und soziale Instabilit\u00e4t.<\/p>\n<p>Heute beobachten wir etwas \u00c4hnliches in den USA. Dieses Land ist nach wie vor die st\u00e4rkste Einzelmacht im internationalen System, doch innenpolitische Konflikte schr\u00e4nken den au\u00dfenpolitischen Handlungsspielraum zunehmend ein. Unterdessen stellt China die innere Stabilit\u00e4t und Entwicklung in den Mittelpunkt seines strategischen Denkens \u2013 gerade weil die chinesische F\u00fchrung davon ausgeht, dass innere Geschlossenheit letztlich auch die St\u00e4rke nach au\u00dfen bestimmt.<\/p>\n<p>Dieselbe Logik lag dem Kalten Krieg zugrunde, denn nachdem Washington und Moskau riesige Atomwaffenarsenale angeh\u00e4uft hatten, wurde ein direkter milit\u00e4rischer Konflikt irrational. Stattdessen entwickelte sich die Konfrontation entsprechend dem, was George Kennan als &#8222;Eind\u00e4mmung&#8220; bezeichnete: den sowjetischen Einfluss zu begrenzen und auf zahlreichen Ebenen Druck auszu\u00fcben, ohne einen direkten Krieg zwischen den Superm\u00e4chten zu riskieren.<\/p>\n<p>Dieses Modell sollte jedoch nicht idealisiert werden. Der &#8222;Kalte Krieg&#8220; blieb im politischen Sinne nach wie vor ein Krieg, und das Ziel der Gegner der Sowjetunion bestand nicht einfach in friedlicher Koexistenz, sondern darin, den Gegner einzud\u00e4mmen und letztlich zu neutralisieren.<\/p>\n<p>Aus Moskauer Sicht richtete sich dieser Kampf gegen Russland selbst, das in jener historischen Phase politisch und wirtschaftlich in Form des Sowjetstaates existierte.<\/p>\n<p>Die durch die nukleare Abschreckung entstandene relative Stabilit\u00e4t f\u00f6rderte zweifellos ein gewisses Ma\u00df an gegenseitigem Respekt, da sie beide Seiten dazu zwang, selbst unter den Bedingungen schwerwiegender Krisen nach friedlichen L\u00f6sungen zu suchen. All dies \u00e4nderte jedoch nichts am grundlegenden strategischen Ziel des Westens \u2013 dem Sieg \u00fcber den sowjetischen Gegner. Als die Sowjetunion aufh\u00f6rte zu existieren, interpretierten die westlichen Hauptst\u00e4dte dies daher nat\u00fcrlich als Erreichung dieses Ziels; doch der Sieg erwies sich als unvollst\u00e4ndig.<\/p>\n<p>Russland hatte zwar den geopolitischen Machtkampf verloren, war jedoch im klassischen Sinne nicht besiegt worden. Sein Staatsgebiet wurde nicht besetzt, seine Streitkr\u00e4fte hatten nicht kapituliert. Daher konnten die Russen zu Recht davon ausgehen, dass die Ereignisse von 1989 bis 1991 auf Entscheidungen beruhten, die in Moskau selbst getroffen worden waren, und nicht auf Bedingungen, die ein siegreicher Gegner diktiert hatte \u2013 und dieser Unterschied erwies sich als au\u00dferordentlich wichtig.<\/p>\n<p>Das erkl\u00e4rt auch, warum Vergleiche mit Frankreich nach 1815 oder Deutschland nach 1945 irref\u00fchrend sind. Beide L\u00e4nder waren zun\u00e4chst milit\u00e4risch besiegt worden, bevor sie in neue, von den Siegerm\u00e4chten geschaffene internationale Ordnungen eingebunden wurden.<\/p>\n<p>So wurde Frankreich nach der \u00c4ra Napoleons wieder in die europ\u00e4ische Ordnung integriert, weil zwischen Russland, Gro\u00dfbritannien, \u00d6sterreich und Preu\u00dfen recht schnell Interessenkonflikte entstanden. Paris konnte dadurch im &#8222;Europ\u00e4ischen M\u00e4chtekonzert&#8220; eine wichtige Rolle beim Ausgleich der Kr\u00e4fte \u00fcbernehmen.<\/p>\n<p>Nach 1991 gab es nichts Vergleichbares. Die westliche Koalition war au\u00dferordentlich geeint und unter US-F\u00fchrung in der NATO organisiert. Es existierte kein inneres Kr\u00e4ftegleichgewicht, innerhalb dessen Russland zu einem unverzichtbaren Partner h\u00e4tte werden k\u00f6nnen.<\/p>\n<p>Der Vergleich mit Westdeutschland nach 1945 ist noch weniger \u00fcberzeugend. Westdeutschland trat der NATO und den sich bildenden europ\u00e4ischen Institutionen bei, w\u00e4hrend auf seinem Territorium weiterhin ausl\u00e4ndische Truppen stationiert waren und seine Souver\u00e4nit\u00e4t infolge der milit\u00e4rischen Niederlage erheblich eingeschr\u00e4nkt blieb. Russland h\u00e4tten keine vergleichbaren Bedingungen auferlegt werden k\u00f6nnen.<\/p>\n<p>Nach 1991 blieb das zentrale Problem ungel\u00f6st: Der Westen sah sich als Sieger des Kalten Krieges und wollte eine politische Ordnung schaffen, die diesen Sieg widerspiegelte. Russland hingegen sah sich als souver\u00e4ne Gro\u00dfmacht, die freiwillig auf die fr\u00fchere Konfrontation verzichtet hatte, und rechnete damit, auf dieser Grundlage an der neuen Ordnung teilzunehmen. Diese Vorstellungen waren jedoch miteinander unvereinbar.<\/p>\n<p>Russland sah in der Politik des Westens bald weniger einen Versuch, Russland zu integrieren, als vielmehr das Bestreben, die durch den Zusammenbruch der Sowjetunion entstandenen Vorteile zu festigen und sicherzustellen, dass Russland die westliche Vorherrschaft nie wieder in Frage stellen k\u00f6nne. Die NATO-Erweiterung war der deutlichste Ausdruck dieser Politik.<\/p>\n<p>Die Entscheidung \u00fcber die Erweiterung des B\u00fcndnisses nach Osten wurde im Januar 1994 getroffen, nur zwei Jahre nach dem Zusammenbruch der Sowjetunion. Aus Moskauer Sicht wurde die milit\u00e4rische Infrastruktur einer Organisation, die zur Eind\u00e4mmung der UdSSR geschaffen worden war, nun auf Gebiete ausgeweitet, aus denen sich die sowjetischen Truppen freiwillig zur\u00fcckgezogen hatten.<\/p>\n<p>Westliche Regierungen beharrten darauf, die Erweiterung diene ausschlie\u00dflich der Verteidigung, und souver\u00e4ne Staaten h\u00e4tten das uneingeschr\u00e4nkte Recht, ihre B\u00fcndnisse selbst zu w\u00e4hlen. F\u00fcr Moskau waren diese Argumente jedoch nie \u00fcberzeugend. Russische Entscheidungstr\u00e4ger betrachteten die NATO-Erweiterung zunehmend als die Schaffung einer territorialen und milit\u00e4rischen Basis, die im Falle einer k\u00fcnftigen Konfrontation gegen Russland eingesetzt werden k\u00f6nnte. Genau darin lag der 1991 entstandene Widerspruch.<\/p>\n<p>Der Kalte Krieg endete ohne eine Niederlage Russlands. Dennoch entwickelte sich die nach 1991 entstandene Ordnung zunehmend so, als w\u00e4re Russland besiegt worden. Der Westen erwartete von Moskau, die strategischen Folgen einer Niederlage zu akzeptieren, die Russland selbst nie erlitten hatte.<\/p>\n<p>Dass Russland dazu nicht bereit war, \u00fcberrascht kaum. Die Konfrontation, die Mitte der 2010er-Jahre offen zutage trat, entstand daher keineswegs aus dem Nichts. Ihre Grundlagen waren viel fr\u00fcher gelegt worden \u2013 in den ungel\u00f6sten Folgen des friedlichen Endes des Kalten Krieges.<\/p>\n<p>Der August 1991 schloss also nicht nur ein Kapitel der russisch-westlichen Beziehungen, sondern bereitete zugleich das n\u00e4chste vor, weil die Konfrontation weder mit einer ausgehandelten Einigung auf Augenh\u00f6he noch mit einer eindeutigen Niederlage eines der Beteiligten endete.<\/p>\n<p><em>\u00dcbersetzt aus dem <a href=\"https:\/\/swentr.site\/russia\/644677-august-1991-russia-west\/\" target=\"_blank\" rel=\"noopener noreferrer\">Englischen<\/a>.<\/em><\/p>\n<p><em><strong>Timofei Bordatschow<\/strong><\/em><em> ist der Programmdirektor des Waldai-<\/em><em>K<\/em><em>lubs.<\/em><\/p>\n<p><strong>Mehr zum Thema \u2013<\/strong>\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de-rtnews.com\/russland\/215991-vor-33-jahren-begann-russlands-katastrophe\/\">Vor 33 Jahren begann Russlands Katastrophe<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7cidbm\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Von Timofei Bordatschow Seit den dramatischen Ereignissen vom August 1991 in Moskau sind nun 35 Jahre vergangen. Sie markierten deutlicher als alle nachfolgenden Deklarationen und diplomatischen Zeremonien das Ende jener Epoche, die wir als &#8222;Kalten Krieg&#8220; bezeichnen. Der gescheiterte Versuch des &#8222;Augustputsches&#8220;, der auf den Erhalt der Sowjetunion abzielte, machte eine Fortsetzung der bisherigen Konfrontation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Von Timofei Bordatschow Seit den dramatischen Ereignissen vom August 1991 in Moskau sind nun 35 Jahre vergangen. Sie markierten deutlicher als alle nachfolgenden Deklarationen und diplomatischen Zeremonien das Ende jener Epoche, die wir als &#8222;Kalten Krieg&#8220; bezeichnen. Der gescheiterte Versuch des &#8222;Augustputsches&#8220;, der auf den Erhalt der Sowjetunion abzielte, machte eine Fortsetzung der bisherigen Konfrontation&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20141"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}