{"id":20208,"date":"2026-08-31T13:02:18","date_gmt":"2026-08-31T11:02:18","guid":{"rendered":"https:\/\/meiser-tv.de\/news\/moderne-sklaverei-bei-enpal-berichterstattung-des-manager-magazins-voll-zulaessig-a-8a4978f3-37f7-4891-8e53-a45021d0039f\/"},"modified":"2026-08-31T13:02:18","modified_gmt":"2026-08-31T11:02:18","slug":"moderne-sklaverei-bei-enpal-berichterstattung-des-manager-magazins-voll-zulaessig-a-8a4978f3-37f7-4891-8e53-a45021d0039f","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/news\/moderne-sklaverei-bei-enpal-berichterstattung-des-manager-magazins-voll-zulaessig-a-8a4978f3-37f7-4891-8e53-a45021d0039f\/","title":{"rendered":"\u201eModerne Sklaverei\u201c bei Enpal: Berichterstattung des manager magazins voll zul\u00e4ssig"},"content":{"rendered":"<div>Enpal und Gr\u00fcnder Mario Kohle nehmen im Berufungsverfahren vor dem Kammergericht Berlin s\u00e4mtliche Unterlassungsantr\u00e4ge zur\u00fcck \u2013 in allen 18 Punkten. Die Recherche ist ab sofort wieder vollst\u00e4ndig abrufbar.<\/div>","protected":false},"excerpt":{"rendered":"<div>Enpal und Gr\u00fcnder Mario Kohle nehmen im Berufungsverfahren vor dem Kammergericht Berlin s\u00e4mtliche Unterlassungsantr\u00e4ge zur\u00fcck \u2013 in allen 18 Punkten. Die Recherche ist ab sofort wieder vollst\u00e4ndig abrufbar.<\/div>","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[18],"tags":[],"class_list":["post-20208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Enpal und Gr\u00fcnder Mario Kohle nehmen im Berufungsverfahren vor dem Kammergericht Berlin s\u00e4mtliche Unterlassungsantr\u00e4ge zur\u00fcck \u2013 in allen 18 Punkten. Die Recherche ist ab sofort wieder vollst\u00e4ndig abrufbar.","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20208"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}