{"id":20450,"date":"2026-09-01T17:03:44","date_gmt":"2026-09-01T15:03:44","guid":{"rendered":"https:\/\/meiser-tv.de\/uncategorized\/das-wichtigste-aus-xis-rede-beim-sco-gipfel\/"},"modified":"2026-09-01T17:03:44","modified_gmt":"2026-09-01T15:03:44","slug":"das-wichtigste-aus-xis-rede-beim-sco-gipfel","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/uncategorized\/das-wichtigste-aus-xis-rede-beim-sco-gipfel\/","title":{"rendered":"Das Wichtigste aus Xis Rede beim SCO-Gipfel"},"content":{"rendered":"<div>\n<p class=\"wp-block-paragraph\">Beim SCO-Gipfel in Bischkek hat Chinas Pr\u00e4sident Xi Jinping <a href=\"https:\/\/www.fmprc.gov.cn\/eng\/xw\/zyxw\/202609\/t20260901_12014036.html\" data-type=\"link\" data-id=\"https:\/\/www.fmprc.gov.cn\/eng\/xw\/zyxw\/202609\/t20260901_12014036.html\" target=\"_blank\" rel=\"noopener\">deutlich gemacht<\/a>, wohin sich das B\u00fcndnis entwickeln soll: <strong>weg von einem rein regionalen Zusammenschluss, hin zu einem eigenst\u00e4ndigen wirtschaftlichen, technologischen und sicherheitspolitischen Machtzentrum in einer multipolaren Welt.<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><strong>Xi Jinping will die Shanghaier Organisation f\u00fcr Zusammenarbeit deutlich ausbauen und als Gegenpol in einer zunehmend multipolaren Welt positionieren.<\/strong> Die SCO solle wirtschaftlich enger zusammenarbeiten, ihre eigene Sicherheitsarchitektur st\u00e4rken und unabh\u00e4ngiger von westlich dominierten Strukturen werden.<\/p>\n<p><script async src=\"https:\/\/telegram.org\/js\/telegram-widget.js?24\" data-telegram-post=\"uncutnews_schlagzeilen\/6654\" data-width=\"100%\"><\/script><\/p>\n<p class=\"wp-block-paragraph\">Besonders hervorzuheben sind die angek\u00fcndigte <strong>Vertiefung der Zusammenarbeit bei Handel, Energie, Transport und Investitionen<\/strong>, ein gemeinsames internationales <strong>KI-Kooperationszentrum<\/strong>, 100 Technologieprojekte innerhalb von drei Jahren sowie ein massiver Ausbau von Solar- und Windenergie. China will au\u00dferdem den Transkaspischen Transportkorridor st\u00e4rken und ein China-SCO-Zentrum f\u00fcr die wirtschaftliche Zusammenarbeit von H\u00e4fen schaffen.<\/p>\n<p class=\"wp-block-paragraph\">Im Sicherheitsbereich fordert Xi ein gemeinsames Vorgehen gegen Terrorismus, Separatismus, Extremismus und organisierte Kriminalit\u00e4t, will die Kooperation aber ausdr\u00fccklich auch auf <strong>Informationssicherheit, biologische Sicherheit und Weltraumsicherheit<\/strong> ausweiten. Die vier geplanten SCO-Sicherheitszentren sollen m\u00f6glichst bald ihre Arbeit aufnehmen.<\/p>\n<p class=\"wp-block-paragraph\">Politisch ist Xis Botschaft besonders deutlich: <strong>Externe M\u00e4chte sollen sich nicht in die inneren Angelegenheiten der SCO-Staaten einmischen.<\/strong> Regionale Probleme sollen von den beteiligten Staaten selbst und durch Dialog gel\u00f6st werden. Die SCO soll zugleich eine gr\u00f6\u00dfere Rolle bei der Gestaltung einer <strong>\u201emultipolaren Welt\u201c und einer neuen globalen Ordnung<\/strong> spielen.<\/p>\n<p class=\"wp-block-paragraph\">Auch bei <strong>Ukraine, Nahost und Afghanistan<\/strong> will China die Abstimmung innerhalb der SCO verst\u00e4rken und politische L\u00f6sungen f\u00f6rdern.<\/p>\n<p class=\"wp-block-paragraph\">Der Kern der Rede lautet damit: <strong>Die SCO soll sich von einem regionalen Zusammenschluss immer st\u00e4rker zu einem eigenst\u00e4ndigen wirtschaftlichen, technologischen und sicherheitspolitischen Machtzentrum entwickeln \u2013 mit China als treibender Kraft und einer ausdr\u00fccklich multipolaren Weltordnung als Ziel.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Offizielle <a href=\"https:\/\/www.fmprc.gov.cn\/eng\/xw\/zyxw\/202609\/t20260901_12014036.html\" data-type=\"link\" data-id=\"https:\/\/www.fmprc.gov.cn\/eng\/xw\/zyxw\/202609\/t20260901_12014036.html\" target=\"_blank\" rel=\"noopener\">Rede von Xi Jinping<\/a> beim chinesischen Au\u00dfenministerium<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Beim SCO-Gipfel in Bischkek hat Chinas Pr\u00e4sident Xi Jinping deutlich gemacht, wohin sich das B\u00fcndnis entwickeln soll: weg von einem rein regionalen Zusammenschluss, hin zu einem eigenst\u00e4ndigen wirtschaftlichen, technologischen und sicherheitspolitischen Machtzentrum in einer multipolaren Welt. Xi Jinping will die Shanghaier Organisation f\u00fcr Zusammenarbeit deutlich ausbauen und als Gegenpol in einer zunehmend multipolaren Welt positionieren. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Beim SCO-Gipfel in Bischkek hat Chinas Pr\u00e4sident Xi Jinping deutlich gemacht, wohin sich das B\u00fcndnis entwickeln soll: weg von einem rein regionalen Zusammenschluss, hin zu einem eigenst\u00e4ndigen wirtschaftlichen, technologischen und sicherheitspolitischen Machtzentrum in einer multipolaren Welt. Xi Jinping will die Shanghaier Organisation f\u00fcr Zusammenarbeit deutlich ausbauen und als Gegenpol in einer zunehmend multipolaren Welt positionieren.&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20450"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}