{"id":20467,"date":"2026-09-01T19:03:08","date_gmt":"2026-09-01T17:03:08","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/russisches-aussenministerium-warnung-an-auslaender-kiew-zu-verlassen-bleibt-aktuell\/"},"modified":"2026-09-01T19:03:08","modified_gmt":"2026-09-01T17:03:08","slug":"russisches-aussenministerium-warnung-an-auslaender-kiew-zu-verlassen-bleibt-aktuell","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/russisches-aussenministerium-warnung-an-auslaender-kiew-zu-verlassen-bleibt-aktuell\/","title":{"rendered":"Russisches Au\u00dfenministerium: Warnung an Ausl\u00e4nder, Kiew zu verlassen, bleibt aktuell"},"content":{"rendered":"<div>\n<p>Die Warnung des russischen Au\u00dfenministeriums an Vertreter der diplomatischen Missionen und Ausl\u00e4nder, Kiew im Zusammenhang mit den russischen Schl\u00e4gen auf Milit\u00e4robjekte zu verlassen, bleibe weiterhin aktuell. Dies <a href=\"https:\/\/www.kommersant.ru\/doc\/8923019\" target=\"_blank\" rel=\"noopener noreferrer\">erkl\u00e4rte<\/a> Maria Sacharowa, die Sprecherin des Au\u00dfenamtes, am Dienstag bei einer Pressekonferenz am Rande des \u00d6stlichen Wirtschaftsforums in Wladiwostok. Sie wies darauf hin, dass Moskau bereits im Mai ausl\u00e4ndische B\u00fcrger in Kiew, einschlie\u00dflich Diplomaten, zur Evakuierung aufgerufen habe. Grund daf\u00fcr sei &#8222;der \u00dcbergang der russischen Streitkr\u00e4fte zu systematischen und konsequenten Angriffen auf die milit\u00e4rische Infrastruktur der Ukraine&#8220;. Sie betonte, dass es sich dabei um Moskaus Reaktion auf die Intensivierung der ukrainischen Angriffe auf Wohngebiete und zivile Infrastruktur in russischen Regionen handele.<\/p>\n<p>Die Warnung war urspr\u00fcnglich am 25. Mai ergangen, nach dem Drohnenangriff der ukrainischen Streitkr\u00e4fte in der Nacht zum 22. Mai auf das Studentenwohnheim in der Stadt Starobelsk in der Volksrepublik Lugansk. Infolge der Attacke kamen 21 Zivilisten ums Leben und mehr als 60 wurden verletzt.<\/p>\n<p>In einer offiziellen Stellungnahme <a href=\"https:\/\/mid.ru\/ru\/foreign_policy\/news\/2111935\/\" target=\"_blank\" rel=\"noopener noreferrer\">betonte<\/a> das russische Au\u00dfenministerium, dass es sich bei dem Angriff um eine grobe Verletzung des V\u00f6lkerrechts gehandelt habe. In diesem Zusammenhang k\u00fcndigte Moskau systematische Angriffe gegen Objekte der ukrainischen R\u00fcstungsindustrie und Kommandostellen in der ukrainischen Hauptstadt an. &#8222;Da oben genannte Objekte \u00fcber ganz Kiew verteilt sind, informieren wir ausl\u00e4ndische B\u00fcrger, darunter das Personal von diplomatischen Vertretungen und internationalen Organisationen \u00fcber die Notwendigkeit, die Stadt m\u00f6glichst schnell zu verlassen&#8220;, hie\u00df es in der Erkl\u00e4rung.\u00a0<\/p>\n<p>Am selben Tag telefonierte Russlands Au\u00dfenminister Sergei Lawrow mit seinem US-Amtskollegen Marco Rubio. Dabei <a href=\"https:\/\/mid.ru\/ru\/foreign_policy\/news\/2112032\/\" target=\"_blank\" rel=\"noopener noreferrer\">gab<\/a> Lawrow bekannt, dass die russische Armee mit systematischen Schl\u00e4gen gegen milit\u00e4rische Objekte in Kiew begonnen habe. Damit reagiere Moskau &#8222;auf die andauernden Terroranschl\u00e4ge des Kiewer Regimes gegen Zivilisten und zivile Objekte auf russischem Territorium&#8220;.<\/p>\n<p>Am 26. Mai 2026 <a href=\"https:\/\/www.interfax.ru\/russia\/1091885\" target=\"_blank\" rel=\"noopener noreferrer\">merkte<\/a> Maria Sacharowa an, dass eine Warnung vor den Angriffen auf Milit\u00e4rziele in Kiew notwendig sei, um die internationale Gemeinschaft zu informieren und so sp\u00e4tere Anschuldigungen gegen Moskau zu vermeiden.<\/p>\n<p>Als Reaktion auf den Aufruf der russischen Beh\u00f6rden betonte die Europ\u00e4ische Union, dass sie ihre diplomatische Vertretung in Kiew nicht evakuieren werde. Anita Hipper, die Sprecherin der EU-Kommission, <a href=\"https:\/\/www.aa.com.tr\/en\/russia-ukraine-war\/eu-says-diplomats-will-remain-in-kyiv-despite-russian-warning\/3949072\" target=\"_blank\" rel=\"noopener noreferrer\">erkl\u00e4rte<\/a>, dass die EU &#8222;ihre diplomatische Pr\u00e4senz in Kiew aufrechterhalten&#8220; und &#8222;ihre milit\u00e4rische Unterst\u00fctzung f\u00fcr die Ukraine sogar noch verst\u00e4rken&#8220; werde.<\/p>\n<p>Auch die US-Botschaft in Kiew weigerte sich, ihr Personal zu evakuieren. &#8222;Die US-Botschaft ist ge\u00f6ffnet. Unsere Arbeit l\u00e4uft unver\u00e4ndert weiter&#8220;, <a href=\"https:\/\/x.com\/USEmbassyKyiv\/status\/2059899088972263897\" target=\"_blank\" rel=\"noopener noreferrer\">hie\u00df<\/a> es in einer Erkl\u00e4rung auf X.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a href=\"https:\/\/de-rtnews.com\/russland\/281192-mass-geduld-ist-voll-moskau\/\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;Ma\u00df der Geduld ist voll&#8220;: Moskau k\u00fcndigt systematische Angriffe auf milit\u00e4rische Ziele in Kiew an<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v78547s\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Warnung des russischen Au\u00dfenministeriums an Vertreter der diplomatischen Missionen und Ausl\u00e4nder, Kiew im Zusammenhang mit den russischen Schl\u00e4gen auf Milit\u00e4robjekte zu verlassen, bleibe weiterhin aktuell. Dies erkl\u00e4rte Maria Sacharowa, die Sprecherin des Au\u00dfenamtes, am Dienstag bei einer Pressekonferenz am Rande des \u00d6stlichen Wirtschaftsforums in Wladiwostok. Sie wies darauf hin, dass Moskau bereits im Mai [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Die Warnung des russischen Au\u00dfenministeriums an Vertreter der diplomatischen Missionen und Ausl\u00e4nder, Kiew im Zusammenhang mit den russischen Schl\u00e4gen auf Milit\u00e4robjekte zu verlassen, bleibe weiterhin aktuell. Dies erkl\u00e4rte Maria Sacharowa, die Sprecherin des Au\u00dfenamtes, am Dienstag bei einer Pressekonferenz am Rande des \u00d6stlichen Wirtschaftsforums in Wladiwostok. Sie wies darauf hin, dass Moskau bereits im Mai&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20467"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}