{"id":20480,"date":"2026-09-01T22:03:01","date_gmt":"2026-09-01T20:03:01","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/es-ist-zeit-die-ukrainer-um-entschuldigung-zu-bitten\/"},"modified":"2026-09-01T22:03:01","modified_gmt":"2026-09-01T20:03:01","slug":"es-ist-zeit-die-ukrainer-um-entschuldigung-zu-bitten","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/es-ist-zeit-die-ukrainer-um-entschuldigung-zu-bitten\/","title":{"rendered":"Es ist Zeit, die Ukrainer um Entschuldigung zu bitten"},"content":{"rendered":"<div>\n<p><em>Von Ted Snider<\/em><\/p>\n<p>Am 25.\u00a0Juni befahl der ukrainische Pr\u00e4sident Wladimir Selenskij eine &#8222;40-t\u00e4gige Einflussoperation&#8220;, die den Einsatz von Drohnen gegen Ziele tief im Inneren Russlands umfasste. Das Ziel war laut Selenskij, Russland zu zwingen, &#8222;den Krieg zu beenden&#8220;, und aus einer f\u00fcr die Ukraine g\u00fcnstigen Position wieder Verhandlungen aufzunehmen.<\/p>\n<p>Das scheint keinen Erfolg gehabt zu haben. Tats\u00e4chlich konnte Russland drei ukrainische Schw\u00e4chen ausnutzen, um seine Position zu st\u00e4rken.<\/p>\n<p>Die erste ist der gef\u00e4hrliche Mangel an Personal, der in den Linien, die die St\u00e4dte des &#8222;Festungsg\u00fcrtels&#8220; des Landes sch\u00fctzen, L\u00fccken hinterlassen hat. Im Verlauf des Sommers r\u00fcckte Russland best\u00e4ndig weiter auf sie vor und hat vielleicht die wichtige Stadt Konstantinowka genommen. Wenn es f\u00e4llt oder gefallen ist, d\u00fcrfte die \u00fcbrigen St\u00e4dte in diesem G\u00fcrtel ein \u00e4hnliches Schicksal erwarten.<\/p>\n<p>Gleich ernst wie die Knappheit des Personals ist die der Luftabwehrmunition. Der Nachschub von Patriot-Abfangraketen an die Ukraine liegt bei null oder n\u00e4hert sich diesem Wert, und die russischen ballistischen und Hyperschallraketen scheinen jetzt nach Wunsch Ziele in der Ukraine zu treffen. Die USA k\u00f6nnen keine abtreten. An einem einzigen Tag der Gefechte in Iran verbrauchen sie bis zu 50 Patriot-Abfangraketen. Sie haben hunderte davon verbraucht und vielleicht noch weniger als 800 \u00fcbrig. Da gibt es nichts zu berichten: Die Abfangquote n\u00e4hert sich null. Die Ukraine verliert den Krieg auf der Langstrecke, insbesondere, weil der Schaden, den ukrainische Drohnen anrichten, bedeutend kleiner ist als der Schaden durch russische Raketen.<\/p>\n<p>Die dritte Schw\u00e4che sind die Probleme der Ukraine beim Abschuss nicht nur russischer Raketen, sondern russischer Drohnen. Das neue, mit einem D\u00fcsentriebwerk versehene Modell der russischen Geran-Drohnen erreicht Geschwindigkeiten, die jene ukrainischer Abfangdrohnen weit \u00fcbertreffen. Diese Hybride aus Drohnen und Lenkraketen verw\u00fcsten den Hafen von Odessa und erschweren es, Waffen in die Ukraine und Produkte von Landwirtschaft und Bergbau herauszubringen.<\/p>\n<p>Es sieht so aus, als w\u00e4re die Ukraine, die den Krieg in der Luft, den am Boden und den Wirtschaftskrieg verliert, dabei, zuerst einzuknicken und an den Verhandlungstisch zur\u00fcckzukehren. Der tragische Teil daran ist, dass das Angebot, das diesmal auf dem Tisch liegen wird, deutlich schlechter sein k\u00f6nnte als der Frieden, der in den ersten Monaten des Krieges m\u00f6glich gewesen w\u00e4re. Die Ukraine war im Fr\u00fchjahr\u00a02022 bereit, einen Frieden zu g\u00fcnstigen Bedingungen zu verhandeln (tats\u00e4chlich waren es die ukrainischen Unterh\u00e4ndler, die sie entwarfen). Aber die USA und Gro\u00dfbritannien dr\u00e4ngten die Ukraine fort vom Weg der Verhandlungen weiter auf den Kriegspfad.<\/p>\n<p>Alexei Arestowitsch, der Mitglied der ukrainischen Unterh\u00e4ndlergruppe in Istanbul war, sagte 2024, die \u00dcbereinkunft, die in Istanbul erreicht wurde, sei &#8222;zu 90\u00a0Prozent vorbereitet&#8220; gewesen. Der Leiter der ukrainischen Gruppe David Arachamia lieferte eine \u00e4hnliche Einsch\u00e4tzung: Russland sei &#8222;bereit, den Krieg zu beenden, wenn wir\u00a0&#8230; uns verpflichteten, nicht der NATO beizutreten&#8220;. Die Gespr\u00e4che, sagte er, seien auf einer Skala des Erfolgs eine &#8222;acht von zehn&#8220; gewesen. Ein drittes Mitglied der Delegation, Alexander Tschaly, erkl\u00e4rte, die beiden Seiten seien &#8222;sehr nahe dran gewesen im\u00a0&#8230; April, unseren Krieg mit einer friedlichen Regelung zu beenden&#8220;. &#8222;Das war&#8220;, sagte Arestowitsch, &#8222;die vorteilhafteste \u00dcbereinkunft, die wir h\u00e4tten abschlie\u00dfen k\u00f6nnen.&#8220;<\/p>\n<p>Was folgte, war ein umfassender Katalog von Prim\u00e4r- und wichtigen Sekund\u00e4rquellen, dass die USA und Gro\u00dfbritannien die Ukraine dr\u00e4ngten, das Abkommen nicht abzuschlie\u00dfen.<\/p>\n<p>Die Sekund\u00e4rquellen sind offenkundig weniger \u00fcberzeugend als die Prim\u00e4rquellen, da sie sich auf das Zeugnis von Personen verlassen, die nicht dort waren. Aber einige sind der Erw\u00e4hnung wert, aufgrund der Position, die sie innehatten. Selenskijs ehemalige Presseprecherin Julia Mendel sagte, Boris Johnson habe &#8222;die Entscheidung beeinflusst&#8220;, die Verhandlungen zu beenden. Die ehemalige Staatssekret\u00e4rin im Au\u00dfenministerium f\u00fcr politische Angelegenheiten Victoria Nuland, die zum Zeitpunkt des Euromaidan 2014 im Au\u00dfenministerium der Obama-Regierung die f\u00fcr die Ukraine zust\u00e4ndige Person war, betonte, die Verhandlungen von Istanbul seien gescheitert, als &#8222;Leute von au\u00dferhalb der Ukraine&#8220; die Vereinbarung in Frage stellten. Der slowakische Ministerpr\u00e4sident Robert Fico erkl\u00e4rte: &#8222;Es ist belegt, dass ganz am Anfang des Krieges in der Ukraine 2022 der Westen der Ukraine bei mindestens zwei vielversprechenden Gelegenheiten nicht erlaubte, eine Waffenruhe zu fairen Bedingungen abzuschlie\u00dfen.&#8220; Und der damalige Senator J.\u00a0D. Vance erkl\u00e4rte im US-Senat, dass, &#8222;worauf viele Leute, sowohl Kritiker von Wladimir Putin als auch Unterst\u00fctzer der Ukraine, hingewiesen haben, tats\u00e4chlich ein Friedensabkommen auf dem Tisch lag\u00a0&#8230; Und was passierte damit? Die Biden-Regierung dr\u00e4ngte Selenskij, ein Friedensabkommen zur\u00fcckzuweisen.&#8220;<\/p>\n<p>Die Berichterstattung der <em>Ukrajinska Prawda<\/em> enth\u00fcllte zuerst, dass Johnson nach Kiew eilte, um Selenskij zu sagen, dass Putin &#8222;unter Druck gesetzt\u00a0und nicht mit ihm verhandelt&#8220; werden solle, und dass, selbst wenn die Ukraine bereit sei, eine \u00dcbereinkunft mit Russland zu unterschreiben, &#8222;der Westen das nicht war&#8220;. In &#8222;The Russo-Ukrainian War: Follies of Empire&#8220; (der russisch-ukrainische Krieg: Narrheiten des Imperiums) berichtet Richard Sawka von einem vorhergehenden Anruf, in dem Johnson Selenskij sagte, Gro\u00dfbritannien &#8222;werde nicht als Garantiemacht bereitstehen und Selenskij dr\u00e4ngte, das Abkommen abzulehnen&#8220;. Das war, sagte Sakwa, auch &#8222;die Position, die die westlichen F\u00fchrer (Johnson, Biden, Olaf Scholz, Emmanuel Macron und der italienische Ministerpr\u00e4sident Mario Draghi) bei einem gemeinsamen Anruf am 29.\u00a0M\u00e4rz einnahmen, am Tag der Istanbuler Gespr\u00e4che&#8220;. Eine hochrangige Regierungsquelle sagte der britischen <em>Times<\/em>, Gro\u00dfbritannien habe Selenskij gewarnt, sich nicht zu Zugest\u00e4ndnissen n\u00f6tigen zu lassen, und es sei die Position der Briten, er solle nicht &#8222;zu eifrig\u00a0&#8230;\u00a0bei\u00a0einer Beilegung&#8220; sein, und &#8222;die Ukraine muss milit\u00e4risch in der st\u00e4rksten m\u00f6glichen Position sein, ehe diese Gespr\u00e4che stattfinden k\u00f6nnen&#8220;.<\/p>\n<p>Noch gr\u00f6\u00dferes Gewicht muss den neun Prim\u00e4rquellen beigemessen werden, die Teil des ukrainischen Verhandlungsteams, Vermittler oder Berater waren.<\/p>\n<p>Arachamia best\u00e4tigte, dass, als die ukrainische Delegation &#8222;aus Istanbul zur\u00fcckkam, Boris Johnson nach Kiew kam und sagte, wir sollten \u00fcberhaupt nichts mit ihnen unterschreiben, und lasst uns nur k\u00e4mpfen&#8220;. Er f\u00fcgte hinzu, der Westen &#8222;riet uns tats\u00e4chlich dazu, uns nicht auf fl\u00fcchtige Sicherheitsgarantien einzulassen&#8220;. Arestowitsch sagte, der Westen habe die Gespr\u00e4che beendet, da er bereits entschieden habe, die Ukraine als Falle zu nutzen, um Russland zu bek\u00e4mpfen.<\/p>\n<p>Tschaly machte klar, dass es f\u00fcr die Ukraine nur Sicherheitsgarantien g\u00e4be, wenn sie die Verhandlungen in Istanbul abbr\u00e4che. &#8222;Mitte April\u00a02022\u00a0&#8230; erkl\u00e4rten die Regierungschefs der Vereinigten Staaten und Gro\u00dfbritanniens, es sei f\u00fcr ihre Staaten inakzeptabel, zusammen mit der Russischen F\u00f6deration an einem multilateralen Vertrag \u00fcber Sicherheitsgarantien f\u00fcr die Ukraine teilzunehmen. Gleichzeitig sicherten sie ihre Bereitschaft zu, der Ukraine unabh\u00e4ngig oder in einem multilateralen Format ohne die Beteiligung der Russischen F\u00f6deration Sicherheitsgarantien zu geben.&#8220;<\/p>\n<p>Der damalige israelische Ministerpr\u00e4sident Naftali Bennet wurde von Selenskij eingeladen, als Mediator zu dienen. Er betonte, es habe &#8222;eine gute Chance gegeben, eine Waffenruhe zu erreichen&#8220;, aber der Westen habe das &#8222;blockiert&#8220;. Laut Bennett war &#8222;eine Waffenruhe damals in Reichweite, und beide Seiten waren bereit, bedeutende Zugest\u00e4ndnisse zu machen. Gro\u00dfbritannien und die USA vor allem beendeten den Prozess und entschieden f\u00fcr eine Fortsetzung des Krieges.&#8220; (Obwohl Bennet sp\u00e4ter einige dieser Aussagen zur\u00fccknahm und 2023 sagte, es sei &#8222;ungewiss, ob da ein Abschluss gemacht h\u00e4tte werden k\u00f6nnen&#8220;).<\/p>\n<p>Der ehemalige Bundeskanzler Gerhard Schr\u00f6der wurden ebenfalls von Selenskij gebeten, zu vermitteln, Er sagte, &#8222;die Ukrainer stimmten einem Frieden nicht zu, weil es ihnen nicht erlaubt wurde. Sie mussten zu allem, was sie diskutierten, erst die USA fragen. Alles andere wurde in Washington entschieden. Das war fatal.&#8220;<\/p>\n<p>Jean-Daniel Ruch, zum Zeitpunkt der Gespr\u00e4che Schweizer Botschafter in der T\u00fcrkei, war dort, um zur Idee einer Neutralit\u00e4t der Ukraine zu beraten. Er sagte ebenfalls, &#8222;der Westen zog den Verhandlungen den Stecker, die kurz davor standen, zu einer Waffenruhe zu f\u00fchren\u00a0&#8230; Wir hatten eine Waffenruhe schon fast in den H\u00e4nden, und dann sind es die\u00a0USA mit ihren britischen Verb\u00fcndeten die Nein sagen&#8220;.<\/p>\n<p>Auch t\u00fcrkische Regierungsvertreter, die die Gespr\u00e4che beherbergten, best\u00e4tigen, dass der Westen die Gespr\u00e4che entmutigt hat. Der t\u00fcrkische Au\u00dfenminister Mevl\u00fct \u00c7avu\u015fo\u011flu erkl\u00e4rte, die Gespr\u00e4che w\u00e4ren auf Kurs gewesen, den Krieg zu beenden, aber da &#8222;waren solche unter den NATO-Mitgliedsstaaten, die den Krieg fortsetzen wollten, lasst den Krieg weitergehen und Russland schw\u00e4cher werden.&#8220; Der stellvertretende Vorsitzende der t\u00fcrkischen Regierungspartei Numan Kurtulmu\u015f berichtet, dass &#8222;die Vereinigten Staaten eine Verl\u00e4ngerung des Krieges als in ihrem Interesse sehen\u00a0&#8230; Putin [und] Selenskij [waren] bereit zu unterzeichnen, aber jemand wollte das nicht&#8220;.<\/p>\n<p>Vielleicht am entscheidendsten ist der t\u00fcrkische Pr\u00e4sident Recep Tayyip Erdo\u011fan, der in Bezug auf eine Erw\u00e4hnung von Arachmias Aussage durch Putin sagte: &#8222;Offen gesagt, diese Erkl\u00e4rungen von Herrn Putin sind ernst. Wir alle haben bei diesen Gespr\u00e4chen ernsthafte Schritte gemacht, die wir den Istanbul-Prozess nennen werden\u00a0&#8230; Wir haben zusammengearbeitet, ehe der ehemalige britische Premierminister Boris Johnson sich von den Friedensbem\u00fchungen zur\u00fcckzog.&#8220;<\/p>\n<p>W\u00e4hrend Russland in diesem Krieg weiter vordringt, scheint es klar, dass die Ukraine eventuell an den Verhandlungstisch zur\u00fcck gezwungen wird. Sie wird wahrscheinlich ein schlechteres Ergebnis erreichen als jenes, das sie vor vier Jahren aufzugeben gedr\u00e4ngt wurde. Und seitdem wurden Hunderttausende Menschen get\u00f6tet oder verwundet, Millionen sind fortgegangen oder wurden vertrieben, die Wirtschaft, die Umwelt, die Infrastruktur wurden verw\u00fcstet, und Land ging verloren. Es ist an der Zeit,\u00a0die Ukrainer daf\u00fcr um Entschuldigung zu bitten, sie in den ersten Monaten des Krieges vom Pfad der Verhandlungen abgebracht zu haben.<\/p>\n<p><em>\u00dcbersetzung aus dem <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.theamericanconservative.com\/its-time-to-apologize-to-ukrainians\/\">Englischen<\/a>. Zuerst erschienen in The American Conservative<\/em>.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de-rtnews.com\/meinung\/220286-gescheiterte-russisch-ukrainische-friedensverhandlungen-nun-meldet-sich-erdogan\/\">Gescheiterter Frieden 2022: Nun plaudert auch Erdo\u011fan<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5byex1\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Von Ted Snider Am 25.\u00a0Juni befahl der ukrainische Pr\u00e4sident Wladimir Selenskij eine &#8222;40-t\u00e4gige Einflussoperation&#8220;, die den Einsatz von Drohnen gegen Ziele tief im Inneren Russlands umfasste. Das Ziel war laut Selenskij, Russland zu zwingen, &#8222;den Krieg zu beenden&#8220;, und aus einer f\u00fcr die Ukraine g\u00fcnstigen Position wieder Verhandlungen aufzunehmen. Das scheint keinen Erfolg gehabt zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Von Ted Snider Am 25.\u00a0Juni befahl der ukrainische Pr\u00e4sident Wladimir Selenskij eine &#8222;40-t\u00e4gige Einflussoperation&#8220;, die den Einsatz von Drohnen gegen Ziele tief im Inneren Russlands umfasste. Das Ziel war laut Selenskij, Russland zu zwingen, &#8222;den Krieg zu beenden&#8220;, und aus einer f\u00fcr die Ukraine g\u00fcnstigen Position wieder Verhandlungen aufzunehmen. Das scheint keinen Erfolg gehabt zu&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20480"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}