{"id":20511,"date":"2026-09-02T07:03:10","date_gmt":"2026-09-02T05:03:10","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/us-luftwaffe-erteilt-rahmenvertrag-fuer-f-15-jet\/"},"modified":"2026-09-02T07:03:10","modified_gmt":"2026-09-02T05:03:10","slug":"us-luftwaffe-erteilt-rahmenvertrag-fuer-f-15-jet","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/us-luftwaffe-erteilt-rahmenvertrag-fuer-f-15-jet\/","title":{"rendered":"US-Luftwaffe erteilt Rahmenvertrag f\u00fcr F-15-Jet"},"content":{"rendered":"<div>\n<p>Das 1972 entwickelte Kampfflugzeug vom Typ F-15 soll f\u00fcr die US-Luftwaffe bis in die 2030er Jahre fliegen. Wie die\u00a0<em><\/em>US-amerikanische\u00a0<em>Air &amp; Space Forces Magazine<\/em><em>\u00a0<\/em><a href=\"https:\/\/www.airandspaceforces.com\/131-billion-f-15-contract-what-it-means-air-force\/\" target=\"_blank\" rel=\"noopener noreferrer\">berichtet<\/a>, habe das Pentagon am 24.\u00a0August einen entsprechenden Rahmenvertrag mit dem Flugzeughersteller Boeing abgeschlossen.<\/p>\n<p>Der als &#8222;F-15 Eagle Crest&#8220; bezeichnete Vertrag sieht f\u00fcr Washington M\u00f6glichkeiten vor, einzelne Auftr\u00e4ge zum Neubau, Modernisierung, Nachr\u00fcstung und Wartung der entsprechenden Flugzeuge an Boeing in einem Gesamtwert bis zu einer Obergrenze von 131,21\u00a0Milliarden US-Dollar zu vergeben. Die Luftwaffe betonte dabei gegen\u00fcber dem\u00a0<em>Air\u00a0&amp; Space Forces Magazine<\/em>, dass der Betrag f\u00fcr eine Obergrenze f\u00fcr k\u00fcnftigen Bedarf stehe und noch keine Zahlungszusage bedeute.<\/p>\n<p>Bestellungen im Rahmen des Vertrags sind bis zum 24.\u00a0August 2031 mit einer Verl\u00e4ngerungsoption bis 2036 m\u00f6glich. Im laufenden Fiskaljahr wurden allerdings noch keine Maschinen bestellt und nur 343.740\u00a0US-Dollar gebunden.<\/p>\n<p>Der Grund f\u00fcr den weiteren Betrieb der F-15 ist die h\u00f6here Zuladung im Vergleich zu den moderneren F-35-Jets. Letztere m\u00fcssen ihre Waffen innen tragen, um die Stealth-Funktion zu bewahren, w\u00e4hrend die j\u00fcngste Modifikation der F-15, die F-15EX Eagle II bis zu zw\u00f6lf Luft-Luft-Raketen au\u00dfen tragen kann und dabei zus\u00e4tzlich \u00fcber eine h\u00f6here Reichweite und niedrigere Betriebskosten verf\u00fcgt.<\/p>\n<p>Als m\u00f6gliche Importeure der F-15EX werden listet die Mitteilung Japan, Israel, Saudi-Arabien, S\u00fcdkorea, Singapur, Indonesien und Polen auf. Konkrete Auftr\u00e4ge liegen nach <a href=\"https:\/\/www.berliner-zeitung.de\/article\/131-milliarden-fuer-einen-jet-aus-den-70ern-und-polen-steht-auf-der-kundenliste-10347547\" target=\"_blank\" rel=\"noopener noreferrer\">Angaben<\/a> der <em>Berliner Zeitung\u00a0<\/em>bisher allerdings nur aus Israel und den USA vor. Demnach plane Tel Aviv die Beschaffung von 25 F-15 im Wert von 8,58\u00a0Milliarden US-Dollar, w\u00e4hrend Washington die urspr\u00fcngliche Bestellung von 98 auf 268 Maschinen bis 2031 erh\u00f6ht hat. Das polnische Verteidigungsministerium meldete dagegen, bisher keine K\u00e4ufe der F-15EX zu planen.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de-rtnews.com\/international\/286331-usa-verstaerken-taktische-luftstreitkraefte-im\/\">USA verst\u00e4rken taktische Luftstreitkr\u00e4fte im Nahen Osten<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7bdzw4\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das 1972 entwickelte Kampfflugzeug vom Typ F-15 soll f\u00fcr die US-Luftwaffe bis in die 2030er Jahre fliegen. Wie die\u00a0US-amerikanische\u00a0Air &amp; Space Forces Magazine\u00a0berichtet, habe das Pentagon am 24.\u00a0August einen entsprechenden Rahmenvertrag mit dem Flugzeughersteller Boeing abgeschlossen. Der als &#8222;F-15 Eagle Crest&#8220; bezeichnete Vertrag sieht f\u00fcr Washington M\u00f6glichkeiten vor, einzelne Auftr\u00e4ge zum Neubau, Modernisierung, Nachr\u00fcstung und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Das 1972 entwickelte Kampfflugzeug vom Typ F-15 soll f\u00fcr die US-Luftwaffe bis in die 2030er Jahre fliegen. Wie die\u00a0US-amerikanische\u00a0Air &amp; Space Forces Magazine\u00a0berichtet, habe das Pentagon am 24.\u00a0August einen entsprechenden Rahmenvertrag mit dem Flugzeughersteller Boeing abgeschlossen. Der als &#8222;F-15 Eagle Crest&#8220; bezeichnete Vertrag sieht f\u00fcr Washington M\u00f6glichkeiten vor, einzelne Auftr\u00e4ge zum Neubau, Modernisierung, Nachr\u00fcstung und&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20511"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}