{"id":20521,"date":"2026-09-02T08:03:14","date_gmt":"2026-09-02T06:03:14","guid":{"rendered":"https:\/\/meiser-tv.de\/uncategorized\/iran-startet-angriffe-auf-jordanien-bahrain-und-kuwait-und-weitere-updates\/"},"modified":"2026-09-02T08:03:14","modified_gmt":"2026-09-02T06:03:14","slug":"iran-startet-angriffe-auf-jordanien-bahrain-und-kuwait-und-weitere-updates","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/uncategorized\/iran-startet-angriffe-auf-jordanien-bahrain-und-kuwait-und-weitere-updates\/","title":{"rendered":"Iran startet Angriffe auf Jordanien, Bahrain und Kuwait und weitere Updates"},"content":{"rendered":"<div>\n<p class=\"wp-block-paragraph\"><em>Von Tyler Durden<\/em><\/p>\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Iran greift Marinekasernen in Jordanien an und schickt Drohnen auf Bahrain und Kuwait, nachdem Trump neue Luftangriffe angeordnet hat<\/strong><\/p>\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Zusammenfassung<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li><strong><em>Explosionen in Jordanien<\/em><\/strong> <em>im Zuge erster iranischer Vergeltungsma\u00dfnahmen gemeldet,<\/em> <strong><em>Drohnenangriffe auf Bahrain<\/em><\/strong><em>.<\/em><\/li>\n<li><em>Berichte \u00fcber eine<\/em> <strong><em>neue US-Angriffswelle im S\u00fcden des Iran<\/em><\/strong><em>, \u00d6lpreis schie\u00dft in die H\u00f6he<\/em><\/li>\n<li><em>Bessent sagt, die Stra\u00dfe von Hormus werde in zwei Jahren ein \u201e<\/em><strong><em>wertloses St\u00fcck Wasser<\/em><\/strong><em>\u201c sein<\/em><\/li>\n<li><strong><em>Iran bietet bedingten Waffenstillstand an:<\/em><\/strong> <em>Pezeshkian sagt, der Iran werde an den Verhandlungstisch zur\u00fcckkehren, wenn die USA fr\u00fchere Verpflichtungen einhalten, gegen die Teheran nach eigenen Angaben versto\u00dfen habe.<\/em><\/li>\n<li><strong><em>Tanker in der Stra\u00dfe von Hormuz getroffen:<\/em><\/strong> <em>Zwei Supertanker wurden beim Verlassen von Hormuz getroffen, was die Risiken auf dem Energiemarkt versch\u00e4rft.<\/em><\/li>\n<li><strong><em>\u00d6lpreise steigen sprunghaft an:<\/em><\/strong> <em>Brent-Roh\u00f6l stieg \u00fcber<\/em> <strong><em>92 $ pro Barrel<\/em><\/strong><em>.<\/em><\/li>\n<li><strong><em>Dieselversorgung angespannt:<\/em><\/strong> <em>Betriebsst\u00f6rungen in Raffinerien treiben die Dieselpreise und Margen stark in die H\u00f6he.<\/em><\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\">***<\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Iran greift Marinekaserne in Jordanien an, Drohnen auf Bahrain und Kuwait geschickt<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Iranische Staatsmedien berichten, dass die milit\u00e4rischen Vergeltungsma\u00dfnahmen andauern. Die Luft- und Raumfahrtstreitkr\u00e4fte des Korps der Islamischen Revolutionsgarden (IRGC) gaben bekannt, dass sie einen massiven ballistischen Raketenangriff <strong>auf die US-Marinekaserne im Camp Titin<\/strong> gestartet haben, die sich <strong>in der N\u00e4he des Golfs von Akaba in Jordanien<\/strong> befindet \u2013 also in betr\u00e4chtlicher Entfernung, im \u00e4u\u00dfersten S\u00fcdwesten des Landes. Staatliche Medienquellen liefern weitere Details:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Nach Angaben des IRGC wurden bei dem Angriff mehrere milit\u00e4rische Einrichtungen und Kampfhubschrauber zerst\u00f6rt, wobei den US-Streitkr\u00e4ften schwere Verluste zugef\u00fcgt wurden. Die Operation wurde als zweite Welle von Vergeltungsma\u00dfnahmen unter dem Codenamen \u201eYa Rasul Allah\u201c durchgef\u00fchrt.<\/em><\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Und weitere Informationen von der staatlichen Nachrichtenagentur WANA: \u201eDie IRGC erkl\u00e4rte, die Aktion sei als Vergeltung f\u00fcr einen US-Angriff auf ein Wohnhaus w\u00e4hrend einer Hochzeitsfeier in Sirik durchgef\u00fchrt worden, bei dem fast 50 Zivilisten get\u00f6tet oder verletzt wurden, darunter auch Kinder.\u201c Die iranischen Behauptungen \u00fcber US-Opfer werden wie \u00fcblich schwer zu \u00fcberpr\u00fcfen sein, doch laut Nachrichtenagenturen hat das CENTCOM erkl\u00e4rt, es seien keine Opfer zu beklagen:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>US-Beamte sagen, dass <strong>bislang keine US-Opfer durch den iranischen Angriff auf Einrichtungen in Jordanien zu verzeichnen sind<\/strong><\/em><\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Im Zuge der m\u00f6glicherweise noch andauernden CENTCOM-Kampagne der USA ist das Stromnetz im iranischen Hormozgan von einem Stromausfall betroffen. Weitere Sch\u00e4den werden voraussichtlich in den kommenden Stunden ermittelt und bekannt gegeben. Auch Bahrain und Kuwait wurden ins Visier genommen:<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Die iranische Armee hat laut der Nachrichtenagentur Fars Drohnenangriffe auf den US-St\u00fctzpunkt in Bahrain gestartet<\/strong><\/li>\n<li><strong>Die kuwaitische Armee teilt mit, dass die Luftabwehr Angriffe<\/strong> durch feindliche Drohnen abwehrt<\/li>\n<li><strong>Jordanien f\u00e4ngt 10 ballistische Raketen aus dem Iran ab<\/strong>, drei davon schlugen in abgelegenen Gebieten ein: Armee<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\"><strong>Erste unbest\u00e4tigte<\/strong> Aufnahmen eines mutma\u00dflichen Angriffs der IRGC auf einen St\u00fctzpunkt in Jordanien kursieren derzeit weitl\u00e4ufig\u2026<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Footage of an Iranian medium-range ballistic missile hitting a target near Aqaba, Jordan moments ago. <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/OTRmWBiuXL\">pic.twitter.com\/OTRmWBiuXL<\/a><\/p>\n<p>\u2014 OSINTtechnical (@Osinttechnical) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/Osinttechnical\/status\/2094880416108781695?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzung von \u201eX\u201c<\/strong>: Aufnahmen einer iranischen ballistischen Mittelstreckenrakete, die soeben ein Ziel in der N\u00e4he von Akaba in Jordanien getroffen hat.<\/em><\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Iranische Vergeltungsschl\u00e4ge gegen St\u00fctzpunkte in der Region beginnen<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Der Iran schl\u00e4gt bereits zur\u00fcck \u2013 so lauten erste Berichte \u00fcber die offenbar j\u00fcngsten Vergeltungsma\u00dfnahmen, obwohl Pr\u00e4sident Trump zuvor gewarnt hatte, dass die Islamische Republik im Falle einer Reaktion noch h\u00e4rter getroffen werde.<\/p>\n<p class=\"wp-block-paragraph\">\u201eSollte die gescheiterte Nation Iran auf diesen sehr berechtigten Angriff Vergeltungsma\u00dfnahmen ergreifen, wird sie erneut getroffen werden \u2013 und zwar viel h\u00e4rter und in gr\u00f6\u00dferem Ausma\u00df \u2013, aber es wird nicht der gr\u00f6\u00dfte Angriff von allen sein; dieser steht noch in den Startl\u00f6chern, und wenn er vorbei ist, wird von der Islamischen Republik Iran nur noch sehr wenig \u00fcbrig sein!\u201c, erkl\u00e4rte er zuvor.<\/p>\n<p class=\"wp-block-paragraph\">Das Wei\u00dfe Haus deutete an, dass es sich darauf konzentriere, Ziele der IRGC auszuschalten. Dies hat jedoch die erwartete Reaktion ausgel\u00f6st:<\/p>\n<ul class=\"wp-block-list\">\n<li>Fars: <em>Einige arabische Quellen berichten, dass<\/em> <strong><em>in Jordanien eine Explosion zu h\u00f6ren war<\/em><\/strong><em>; von amerikanischen St\u00fctzpunkten in Jordanien waren mehrere Explosionen zu h\u00f6ren<\/em><\/li>\n<li>Die IRGC sagt, <strong>die US-Angriffe w\u00fcrden die Blockade<\/strong> der Stra\u00dfe von Hormus versch\u00e4rfen<\/li>\n<li><strong>Explosion in Erbil<\/strong>, <strong>Irak<\/strong>, zu h\u00f6ren, berichtet Fars<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\">Auch bei den letzten Vergeltungsma\u00dfnahmen waren US-St\u00fctzpunkte in Jordanien das Ziel.<\/p>\n<p class=\"wp-block-paragraph\">Ein Analyst des Atlantic Council weist auf das Offensichtliche hin \u2013 die heutige Aktion ist ein weiteres Anzeichen daf\u00fcr, dass die Regierung immer noch nicht versteht, wie die iranische Regierung und F\u00fchrung denkt (es sei denn, die <em>Absicht<\/em> ist eine tats\u00e4chliche au\u00dfer Kontrolle geratene Eskalation). Danny Citrinowicz <a href=\"https:\/\/x.com\/citrinowicz\/status\/2094850236262797544\" target=\"_blank\" rel=\"noopener\">schreibt<\/a>:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Teheran mit noch verheerenderen Schl\u00e4gen zu drohen, sollte es zur\u00fcckschlagen, d\u00fcrfte eine iranische Reaktion kaum verhindern. Tats\u00e4chlich k\u00f6nnte es genau das Gegenteil bewirken. <strong>Aus Teherans Sicht w\u00fcrde das Ausbleiben einer Reaktion auf einen direkten US-Angriff genau jene Abschreckungsstrategie untergraben, die der Iran seit Monaten aufzubauen versucht<\/strong>. Die iranische F\u00fchrung ist der Ansicht, dass sie zeigen muss, dass amerikanische Milit\u00e4raktionen ihren Preis haben. Das bedeutet, dass der Iran wahrscheinlich zur\u00fcckschlagen wird und m\u00f6glicherweise sogar zu dem Schluss kommt, dass eine umfassendere oder schmerzhaftere Reaktion notwendig ist, um die Abschreckung gegen k\u00fcnftige US-Angriffe wiederherzustellen.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>Das ist das grundlegende Problem an Washingtons Vorgehen: Es geht davon aus, dass ausreichend starke Drohungen den Iran davon \u00fcberzeugen werden, nachzugeben<\/strong>. Teheran k\u00f6nnte jedoch genau die gegenteilige Schlussfolgerung ziehen, <strong>was bedeuten w\u00fcrde, dass ein Einlenken unter Drohungen weitere amerikanische Angriffe nach sich ziehen w\u00fcrde<\/strong>. Drohungen werden dieses Problem nicht l\u00f6sen. Wenn Washington einen weiteren Kreislauf aus Vergeltungsma\u00dfnahmen und Gegenma\u00dfnahmen verhindern will, braucht es eine politische Strategie zur Beendigung der Konfrontation. Andernfalls wird jede Seite weiterhin Gewalt anwenden, um die Abschreckung nach der jeweils vorangegangenen Runde wiederherzustellen \u2013 was einen Eskalationskreislauf schafft, der immer schwieriger zu kontrollieren ist.<\/em><\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Die j\u00fcngsten Enth\u00fcllungen aus dem Pentagon an die \u201eWashington Post\u201c liegen erst wenige Tage zur\u00fcck, und nun das:<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Looks like the high-level Pentagon leaks and resignations of the past week were meant to forestall or prevent exactly what\u2019s happening now. Didn\u2019t work of course. There are no checks on power, unless Israel gets upset. We don\u2019t even have an opposition party to speak of. <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/5m1DaLirOg\">https:\/\/t.co\/5m1DaLirOg<\/a><\/p>\n<p>\u2014 Mark Ames (@MarkAmesExiled) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/MarkAmesExiled\/status\/2094865789970948165?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzungen von \u201eX\u201c<\/strong>: Es sieht so aus, als h\u00e4tten die hochrangigen Indiskretionen aus dem Pentagon und die R\u00fccktritte der vergangenen Woche genau das verhindern sollen, was jetzt gerade geschieht. Das hat nat\u00fcrlich nicht funktioniert. Es gibt keine Kontrollmechanismen f\u00fcr die Macht, es sei denn, Israel regt sich auf. Wir haben nicht einmal eine nennenswerte Oppositionspartei.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em>Heute um 12 Uhr ET haben US-Streitkr\u00e4fte begonnen, Ziele des Korps der Islamischen Revolutionsgarden (IRGC) im Iran anzugreifen. Die Angriffe folgen auf j\u00fcngste Angriffsversuche des IRGC gegen die Handelsschifffahrt in der Stra\u00dfe von Hormus und gegen in der Region stationierte amerikanische Soldaten.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Weitere aktuelle Meldungen via AJ:<\/p>\n<ul class=\"wp-block-list\">\n<li><em>Das US-Milit\u00e4r gibt an,<\/em> <em>Ziele im Iran anzugreifen, als Reaktion auf versuchte Angriffe auf die Schifffahrt, w\u00e4hrend iranische Medien \u00fcber<\/em> <strong><em>Explosionen in Asaluyeh, Jiroft, Bandar Abbas, auf der Insel Qeshm, in Konarak, Chabahar, Jask, Sirik und Lavan<\/em><\/strong> <em>berichten.<\/em><\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li><em>Die iranische Armee und die IRGC versprechen, dass die USA dies bereuen werden und<\/em> <strong><em>f\u00fcr die Aggression eine \u201eharte Strafe\u201c zu erwarten haben<\/em><\/strong><em>.<\/em><\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li>US-Pr\u00e4sident Donald Trump erkl\u00e4rt: \u201eSollte die gescheiterte Nation Iran Vergeltung f\u00fcr diesen v\u00f6llig gerechtfertigten Angriff \u00fcben, wird sie erneut getroffen werden \u2013 und zwar viel h\u00e4rter und in gr\u00f6\u00dferem Umfang\u201c.<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Both WTI and Brent crude are up 5% todat, both now trading above $90 a barrel following the escalation of US military strikes on Iran. <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/hashtag\/economy?src=hash&amp;ref_src=twsrc%5Etfw\">#economy<\/a> <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/hashtag\/oil?src=hash&amp;ref_src=twsrc%5Etfw\">#oil<\/a> <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/hashtag\/energy?src=hash&amp;ref_src=twsrc%5Etfw\">#energy<\/a> <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/hashtag\/markets?src=hash&amp;ref_src=twsrc%5Etfw\">#markets<\/a> <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/IYEohy2RIo\">pic.twitter.com\/IYEohy2RIo<\/a><\/p>\n<p>\u2014 Mohamed A. El-Erian (@elerianm) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/elerianm\/status\/2094864274086621469?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzung von \u201eX\u201c<\/strong>: Sowohl WTI- als auch Brent-Roh\u00f6l haben heute um 5 % zugelegt und werden nach der Eskalation der US-Milit\u00e4rschl\u00e4ge gegen den Iran nun beide \u00fcber 90 US-Dollar pro Barrel gehandelt.<\/em><\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Trump: \u201eGro\u00dfe und m\u00e4chtige Angriffe\u201c als \u201eVergeltungsma\u00dfnahme\u201c f\u00fcr die Verminung der Stra\u00dfe von Hormus<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Der Pr\u00e4sident best\u00e4tigte dies und beschrieb diese neuen Luftangriffe als andauernd sowie als \u201egro\u00df und m\u00e4chtig\u201c\u2026 Er f\u00fcgte hinzu, dass dies eine Vergeltungsma\u00dfnahme f\u00fcr die Verminung der Stra\u00dfe von Hormus durch die Iraner sei. Der vollst\u00e4ndige Beitrag auf Truth Social:<\/p>\n<figure class=\"wp-block-image aligncenter size-large\"><img data-opt-id=307003934  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png\" alt=\"\"><\/figure>\n<p class=\"wp-block-paragraph\">Insbesondere warnt er, dass die Iraner erneut \u201eviel h\u00e4rter\u201c getroffen werden, sollten sie den Forderungen Washingtons nicht nachkommen.<\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Erste Berichte \u00fcber US-Angriffe auf den S\u00fcden des Iran lassen \u00d6lpreis in die H\u00f6he schnellen<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Seltene US-Angriffe gegen den Iran mitten in der US-B\u00f6rsenzeit? Wenn ja, w\u00e4re das ein gewagter Schritt. Einige aktuelle Schlagzeilen:<\/p>\n<ul class=\"wp-block-list\">\n<li>BERICHTE \u00dcBER EXPLOSIONEN IN DEN S\u00dcDLICHEN REGIONEN DES IRAN: STAATSFERNSEHEN<\/li>\n<li>PENTAGON STARTET NEUE ANGRIFFE AUF DEN S\u00dcDEN DES IRAN<\/li>\n<li>Al Arabiya: \u201eDEFENSIVE\u201c BOMBARDIERUNGEN \u2014 Quelle gegen\u00fcber Faytuks<\/li>\n<li>EXPLOSIONEN IN KONARAK IM S\u00dcDOSTEN DES IRAN GEMELDET: FARS<\/li>\n<li>US-STREITKR\u00c4FTE HABEN HEUTE UM 12 UHR ET MIT ANGRIFFEN AUF ZIELE DER IRGC IM IRAN BEGONNEN<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\">Und von Al Hadath: \u201eExplosionen \u00f6stlich von Bandar Abbas und der Insel Qeshm zu h\u00f6ren; f\u00fcnf Explosionen in Qeshm und vier in der N\u00e4he der Stra\u00dfe von Hormuz.\u201c CENTCOM hat best\u00e4tigt:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Heute um 12 Uhr ET begannen US-Streitkr\u00e4fte mit Angriffen auf Ziele des Korps der Islamischen Revolutionsgarden (IRGC) im Iran. Die Angriffe folgen auf j\u00fcngste Angriffsversuche der IRGC gegen die Handelsschifffahrt in der Stra\u00dfe von Hormus und gegen in der Region stationierte amerikanische Soldaten.<\/em><\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Best\u00e4tigung der Angriffe auch von Seiten der <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.aljazeera.com\/news\/liveblog\/2026\/9\/1\/iran-war-live-trump-vows-to-hit-iran-following-first-clash-in-a-month\">Iraner<\/a>:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Der stellvertretende Gouverneur f\u00fcr Sicherheit und Strafverfolgung der Provinz Sistan und Belutschistan sagt, vier Geschosse h\u00e4tten die Bezirke Chabahar und Konarak getroffen, berichtet die iranische Nachrichtenagentur IRNA.<\/em><\/p>\n<\/blockquote>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>General Ali Khalil Abadi best\u00e4tigte die Angriffe mit den Worten: \u201eDerzeit laufen fachliche Untersuchungen, um die Einzelheiten des Vorfalls, m\u00f6gliche Sch\u00e4den und weitere Informationen zu ermitteln.\u201c<\/em><\/p>\n<\/blockquote>\n<p class=\"wp-block-paragraph\">Die \u00d6lpreise schie\u00dfen angesichts der neuen offensichtlichen \u201eSchie\u00dferei\u201c in die H\u00f6he, die bereits in verschiedenen Berichten dieser Woche angek\u00fcndigt wurde. Trump setzt nun offenbar Hegseths Plan in die Tat um:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">WTI n\u00e4hert sich der 90-Dollar-Marke\u2026<\/p>\n<\/blockquote>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img data-opt-id=746284976  fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/2026-09-01_09-24-23.png\" alt=\"\" style=\"aspect-ratio:1.4496693583262088;width:744px;height:auto\"><\/figure>\n<p class=\"wp-block-paragraph\">US-Angriffe auf den Iran fanden fast immer in den Nacht- und fr\u00fchen Morgenstunden statt \u2013 und in der Regel erst nach B\u00f6rsenschluss in den USA, sodass ein Angriff tags\u00fcber in der Tat sehr selten ist\u2026<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Trump is so confident that Bessent can continue suppressing crude oil prices that now is attacking Iran in the middle of US trading hours \u2013 bad mistake, very bad<\/p>\n<p>\u2014 JustDario (@DarioCpx) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/DarioCpx\/status\/2094822531123323266?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzung von \u201eX\u201c<\/strong>: Trump ist so \u00fcberzeugt davon, dass Bessent die Roh\u00f6lpreise weiterhin niedrig halten kann, dass er nun mitten in der US-Handelszeit den Iran angreift \u2013 ein schwerer Fehler, ein sehr schwerer Fehler<\/em><\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Bessent: Hormuz wird in zwei Jahren ein \u201ewertloses St\u00fcck Wasser\u201c sein<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Finanzminister Scott Bessent erkl\u00e4rte den Teilnehmern des Treffens der Finanzminister der G20 in Asheville, North Carolina, dass die F\u00e4higkeit des Iran, die Stra\u00dfe von Hormuz als strategischen Engpass zu nutzen, auf null sinken werde, da \u201e<strong>das \u00d6l k\u00fcnftig \u00fcber Pipelines auf dem Landweg transportiert wird<\/strong>\u201c.<\/p>\n<p class=\"wp-block-paragraph\"><strong>\u201eDie Iraner versuchen, die Stra\u00dfe von Hormuz als Engpass zu nutzen. F\u00fcr die USA ist sie kein Engpass, f\u00fcr viele andere L\u00e4nder jedoch schon. Dieser wird in zwei Jahren umgangen werden. In zwei Jahren wird die <u>Stra\u00dfe von Hormuz ein wertloses St\u00fcck Wasser sein<\/u>. Das \u00d6l wird durch Pipelines \u00fcber Land transportiert werden\u201c, sagte Bessent.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Bessent on Iran:<\/p>\n<p>Iranians are trying to use the Strait of Hormuz as a chokepoint.<\/p>\n<p>It\u2019s not a chokepoint for the US, but it is for many other countries.<\/p>\n<p>That will be bypassed in 2 years. In 2 years, the Strait of Hormuz will be a worthless piece of water.<\/p>\n<p>The oil will be going\u2026 <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/8z9BhNvGku\">pic.twitter.com\/8z9BhNvGku<\/a><\/p>\n<p>\u2014 Clash Report (@clashreport) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/clashreport\/status\/2094786439791653313?ref_src=twsrc%5Etfw\">September 1, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzung von \u201eX\u201c<\/strong>: Bessent zum Thema Iran:<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em>Die Iraner versuchen, die Stra\u00dfe von Hormus als Engpass zu nutzen.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em>F\u00fcr die USA ist sie kein Engpass, f\u00fcr viele andere L\u00e4nder jedoch schon.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em>Das wird in zwei Jahren umgangen werden. In zwei Jahren wird die Stra\u00dfe von Hormus ein wertloses St\u00fcck Wasser sein.<\/em><\/p>\n<p class=\"wp-block-paragraph\"><em>Das \u00d6l wird dann \u00fcber Pipelines auf dem Landweg transportiert werden.<\/em><\/p>\n<p class=\"wp-block-paragraph\">Bessents \u00c4u\u00dferungen von heute Morgen d\u00fcrften f\u00fcr die Leser keine \u00dcberraschung sein, da wir bereits ausf\u00fchrlich \u00fcber die bestehenden Pipelines, die den Hormuz-Sund umgehen, sowie \u00fcber die neuen Pipeline-Projekte berichtet haben, die von den verb\u00fcndeten Produzenten am Golf geplant sind.<\/p>\n<p class=\"wp-block-paragraph\">Allerdings sind diese neuen Initiativen f\u00fcr \u201ealternative Energierouten\u201c mit <strong>einer Vielzahl von Unw\u00e4gbarkeiten<\/strong> behaftet \u2013 insbesondere hinsichtlich der Sicherheit und des Schutzes der Infrastruktur bzw. der Bauarbeiten in einer offensichtlich instabilen Region, der Zusammenarbeit zwischen den Transitstaaten (bei Landrouten) sowie ungeachtet der immensen Kosten.<\/p>\n<p class=\"wp-block-paragraph\">Um nur ein aktuelles Beispiel aus den Schlagzeilen zu nennen:<\/p>\n<p class=\"wp-block-paragraph\">Und da beide genannten L\u00e4nder gerade erst jahrzehntelange \u201eewige Kriege\u201c hinter sich haben und insbesondere Syrien nach wie vor weitgehend zerst\u00f6rt und zersplittert ist, <strong>werden die Bem\u00fchungen, Bessents geplantes Umgehungssystem \u201e\u00fcber Land\u201c<\/strong> \u2013 wie er es nennt \u2013 <strong>zu verwirklichen, sich h\u00f6chstwahrscheinlich weit \u00fcber die Amtszeit der Trump-Regierung hinaus hinziehen.<\/strong><\/p>\n<figure class=\"wp-block-image aligncenter size-large\"><img data-opt-id=1710250036  data-opt-src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/2026-07-23_12-35-32.png\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\"><\/figure>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Pezeshkian: Wir kehren zum Waffenstillstand zur\u00fcck, wenn die USA dies tun<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Der iranische Pr\u00e4sident Masoud Pezeshkian bekr\u00e4ftigte am Dienstag die Bereitschaft seines Landes, die Gespr\u00e4che mit den USA wieder aufzunehmen, machte jedoch deutlich, dass Washington zu seinen fr\u00fcheren Verpflichtungen zur\u00fcckkehren m\u00fcsse.<\/p>\n<p class=\"wp-block-paragraph\">\u201eIch erkl\u00e4re ausdr\u00fccklich: Wenn die Vereinigten Staaten zu ihren Verpflichtungen im Rahmen der \u2026 Absichtserkl\u00e4rung zur\u00fcckkehren, <strong>wird die Islamische Republik Iran unverz\u00fcglich entsprechende Gegenma\u00dfnahmen ergreifen<\/strong>\u201c, sagte Pezeshkian am Rande des Gipfeltreffens der Shanghaier Organisation f\u00fcr Zusammenarbeit (SCO) in Bischkek, Kirgisistan.<\/p>\n<p class=\"wp-block-paragraph\">Es ist bezeichnend, dass er pers\u00f6nlich an dem von Kirgisistan ausgerichteten Gipfel teilnimmt und dort von Pers\u00f6nlichkeiten wie Putin, Xi, Erdogan, UN-Generalsekret\u00e4r Guterres und anderen begr\u00fc\u00dft wird.<\/p>\n<p class=\"wp-block-paragraph\">Pezeshkian <strong>kritisierte die USA dennoch scharf daf\u00fcr, dass sie \u201eihre Verpflichtungen nicht eingehalten haben\u201c<\/strong> im Rahmen des Abkommens, das im Juni scheiterte \u2013 was zu mehreren Wochen sporadischer Vergeltungsschl\u00e4ge f\u00fchrte \u2013, von denen der j\u00fcngste erst zu Beginn dieser Woche stattfand.<\/p>\n<p class=\"wp-block-paragraph\">Pr\u00e4sident Trump erkl\u00e4rte gestern gegen\u00fcber Reportern im Oval Office, dass es eine \u201eReaktion\u201c auf die iranischen Angriffe geben werde, warnte jedoch gleichzeitig, dass dies keine R\u00fcckkehr zu einem umfassenden Krieg bedeuten w\u00fcrde.<\/p>\n<p class=\"wp-block-paragraph\">US-Beamte sprachen davon, mit einer Reihe von unbestimmten Angriffen <strong>\u201edas Gras zu m\u00e4hen\u201c<\/strong>, w\u00e4hrend sie ironischerweise eine Abneigung dagegen haben, wenn jemand den Begriff \u201eewiger Krieg\u201c verwendet.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">It&#8217;s not a &#8222;forever war&#8220;; it&#8217;s just &#8222;mowing the lawn.&#8220;<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/oJTjmdSiHb\">https:\/\/t.co\/oJTjmdSiHb<\/a> <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/t.co\/9JI0lfWaVS\">pic.twitter.com\/9JI0lfWaVS<\/a><\/p>\n<p>\u2014 Brandan P. Buck (@brandan_buck) <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/x.com\/brandan_buck\/status\/2094493400418406592?ref_src=twsrc%5Etfw\">August 31, 2026<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"wp-block-paragraph\"><em><strong>\u00dcbersetzung von \u201eX\u201c<\/strong>: Es ist kein \u201eewiger Krieg\u201c, sondern einfach nur \u201eRasen m\u00e4hen\u201c.<\/em><\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Zwei Supertanker getroffen<\/strong><\/h2>\n<p class=\"wp-block-paragraph\"><strong>Zwei \u00d6l-Supertanker wurden von unbekannten Geschossen getroffen<\/strong>, als sie am fr\u00fchen Dienstagmorgen die Stra\u00dfe von Hormus durchfuhren \u2013 ein Zeichen f\u00fcr eine weitere drastische Eskalation der Feindseligkeiten an der weltweit wichtigsten Energie-Engstelle.<\/p>\n<p class=\"wp-block-paragraph\">Die Angriffe folgen auf die Warnung von Pr\u00e4sident Trump vom Montag, dass weitere Angriffe gegen den Iran weiterhin m\u00f6glich seien. H\u00e4ndler preisen eine <strong>weitere Kriegsrisikopr\u00e4mie<\/strong> ein, wodurch die Brent-Roh\u00f6l-Futures \u00fcber 92 US-Dollar pro Barrel steigen, w\u00e4hrend die Crack-Spreads f\u00fcr US-Diesel die kritische Schwelle von 100 US-Dollar pro Barrel \u00fcberschritten haben.<\/p>\n<p class=\"wp-block-paragraph\">Der maritime Sicherheitsberater Marisks berichtet, dass der <strong>VLCC \u201eSidr\u201c<\/strong> des saudischen Schifffahrtsriesen <strong>Bahri<\/strong> <strong><em>nord\u00f6stlich von Khasab, Oman, getroffen wurde<\/em><\/strong>. Die <strong>von Sinokor betriebene <em>\u201eSenegal Prosperity\u201c<\/em> wurde Berichten zufolge<\/strong> weiter \u00f6stlich von drei Geschossen getroffen. Beide Tanker verlie\u00dfen gerade den maritimen Engpass.<\/p>\n<p class=\"wp-block-paragraph\">UK Maritime Trade Operations best\u00e4tigte separat, dass ein Tanker, der gerade die Durchfahrt durch die Stra\u00dfe von Hormuz hinter sich hatte, drei Geschosstreffer gemeldet habe, nannte jedoch nicht den Namen des Schiffes.<\/p>\n<p class=\"wp-block-paragraph\">Die Brent-Roh\u00f6l-Futures schossen w\u00e4hrend des asiatischen und europ\u00e4ischen Handels aufgrund dieser Nachrichten in die H\u00f6he, wobei der <strong>Referenzpreis um 06:00 Uhr ET deutlich \u00fcber 92 US-Dollar lag.<\/strong><\/p>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img data-opt-id=1073504593  data-opt-src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/brent_1.png\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\" style=\"aspect-ratio:1.1718749650754046;width:600px;height:auto\"><\/figure>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Weitere US-Luftangriffe im Raum, warnt Trump<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">\u201e<strong>Pr\u00e4sident Donald Trump warnte am Montag, dass weitere Luftangriffe m\u00f6glich seien, was den Brent-Preis wieder \u00fcber 91 Dollar pro Barrel steigen lie\u00df und eine weitere Tendenz zur steileren Renditekurve an den globalen Anleihem\u00e4rkten ausl\u00f6ste<\/strong>\u201c, schrieb UBS-Analyst George Redman zuvor.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Die Crack-Spreads f\u00fcr Diesel in den USA lagen um 06:00 Uhr ET \u00fcber 100 Dollar.<\/strong><\/p>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img data-opt-id=947722538  data-opt-src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/crack_0.png\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\" style=\"aspect-ratio:1.3412691485071433;width:602px;height:auto\"><\/figure>\n<p class=\"wp-block-paragraph\">Wie wir bereits ausf\u00fchrlich dargelegt haben, liegt die <strong>Energiekrise nicht unbedingt beim Roh\u00f6l selbst, sondern bei den Raffinerieprodukten<\/strong>. Die Lieferungen von Diesel und Benzin aus der Golfregion sind aufgrund von St\u00f6rungen in der Stra\u00dfe von Hormus zur\u00fcckgegangen, w\u00e4hrend Sch\u00e4den an der russischen Energieinfrastruktur durch ukrainische Einweg-Angriffsdrohnen im Sp\u00e4tsommer eine perfekte Sturmkonstellation auf den globalen Raffineriem\u00e4rkten ausgel\u00f6st haben.<\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>\u201eDiesel im Epizentrum der Versorgungsengp\u00e4sse\u201c<\/strong><\/h2>\n<p class=\"wp-block-paragraph\">Goldmans Energieexperte Daan Struyven warnte in seinem j\u00fcngsten Bericht, dass \u201e<strong>Diesel im Epizentrum der Versorgungsengp\u00e4sse steht<\/strong>\u201c.<\/p>\n<p class=\"wp-block-paragraph\">\u201e<strong>Die zunehmenden Angriffe auf Raffinerien im Nahen Osten und in Russland haben die ohnehin schon angespannte globale Raffineriekapazit\u00e4t weiter eingeschr\u00e4nkt und die Margen f\u00fcr Raffinerieprodukte auf neue H\u00f6chstst\u00e4nde getrieben<\/strong>\u201c, schrieben Struyven und Yulia Zhestkova Grigsby in der Analyse und f\u00fcgten hinzu: \u201e<strong>Diesel bleibt das Epizentrum der Kursrallye<\/strong>.\u201c<\/p>\n<p class=\"wp-block-paragraph\">Struyven und sein Team sch\u00e4tzen, dass <strong>die weltweite Raffinerieauslastung gegen\u00fcber dem Vorjahr um 7 Millionen Barrel pro Tag zur\u00fcckgegangen ist<\/strong> und seit M\u00e4rz \u2013 etwa zu dem Zeitpunkt, als die USA die Operation \u201eEpic Fury\u201c starteten und die Ukraine ihre Einweg-Drohnenangriffe auf Russlands Energieinfrastruktur verst\u00e4rkte \u2013 im Durchschnitt fast 6 Millionen Barrel pro Tag unter den saisonalen Normwerten lag.<\/p>\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img data-opt-id=67240559  data-opt-src=\"https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/2026-08-31_07-46-54.png\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\" style=\"aspect-ratio:1.4173088541037586;width:624px;height:auto\"><\/figure>\n<p class=\"wp-block-paragraph\">Unterdessen k\u00f6nnte es im Golfraum zu diplomatischen Fortschritten kommen, nachdem der iranische Pr\u00e4sident Masoud Pezeshkian im staatlichen Fernsehen erkl\u00e4rte: \u201eIch sage ganz klar: Sollte die USA zu ihren Verpflichtungen aus der oben genannten Absichtserkl\u00e4rung zur\u00fcckkehren, wird die Islamische Republik Iran ebenfalls unverz\u00fcglich entsprechende Ma\u00dfnahmen ergreifen.\u201c<\/p>\n<p class=\"wp-block-paragraph\">Auch die \u201eOperation Economic Outcast\u201c von Finanzminister Scott Bessent wird intensiviert, da die Trump-Regierung Sanktionen verh\u00e4ngt, um Teheran zur Unterwerfung zu zwingen.<\/p>\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Weitere aktuelle Entwicklungen<\/strong><\/h2>\n<p class=\"wp-block-paragraph\"><em>via Newsquawk\u2026<\/em><\/p>\n<ul class=\"wp-block-list\">\n<li>Der Sprecher des iranischen Au\u00dfenministeriums, Baghaei, sagte, Europa k\u00f6nne keine strategische Autonomie f\u00fcr sich beanspruchen, wenn es den Anweisungen Washingtons folge, und betonte, dass wahre Autonomie bedeute, unabh\u00e4ngige Entscheidungen zu treffen.<\/li>\n<li>Pakistans stellvertretender Premierminister und Au\u00dfenminister traf sich laut dem Journalisten Anas Mallick in Bischkek im Wartezimmer des SCO-Staatschefsrats informell mit dem iranischen Au\u00dfenminister Araghchi.<\/li>\n<li>Der Golf-Kooperationsrat verurteilte laut Al Jazeera die iranischen Angriffe auf Jordanien und erkl\u00e4rte, diese stellten eine direkte Bedrohung f\u00fcr die Sicherheit und Stabilit\u00e4t der Region dar.<\/li>\n<li>Die jemenitischen Streitkr\u00e4fte griffen am fr\u00fchen Dienstagmorgen St\u00fctzpunkte saudischer und emiratischer S\u00f6ldner in Al-Makha und Al-Khuwakh im S\u00fcdwesten des Landes an, wie IRIB berichtete.<\/li>\n<li>Der Vorstandsvorsitzende von Hapag-Lloyd (HLAG GY) erkl\u00e4rte, es sei davon auszugehen, dass die Stra\u00dfe von Hormus auf absehbare Zeit blockiert bleiben werde.<\/li>\n<\/ul>\n<p class=\"wp-block-paragraph\">\n<p class=\"wp-block-paragraph\">***<\/p>\n<p class=\"wp-block-paragraph\">\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Von Tyler Durden Iran greift Marinekasernen in Jordanien an und schickt Drohnen auf Bahrain und Kuwait, nachdem Trump neue Luftangriffe angeordnet hat Zusammenfassung Explosionen in Jordanien im Zuge erster iranischer Vergeltungsma\u00dfnahmen gemeldet, Drohnenangriffe auf Bahrain. Berichte \u00fcber eine neue US-Angriffswelle im S\u00fcden des Iran, \u00d6lpreis schie\u00dft in die H\u00f6he Bessent sagt, die Stra\u00dfe von Hormus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-20521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",723,491,false],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:150\/h:150\/q:mauto\/rt:fill\/g:ce\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:300\/h:204\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",300,204,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",723,491,false],"large":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",723,491,false],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",723,491,false],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",723,491,false],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/cb:Ngjc.d0b\/w:18\/h:12\/q:mauto\/f:best\/dpr:2\/https:\/\/meiser-tv.de\/wp-content\/uploads\/2026\/09\/image2_24.png",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Von Tyler Durden Iran greift Marinekasernen in Jordanien an und schickt Drohnen auf Bahrain und Kuwait, nachdem Trump neue Luftangriffe angeordnet hat Zusammenfassung Explosionen in Jordanien im Zuge erster iranischer Vergeltungsma\u00dfnahmen gemeldet, Drohnenangriffe auf Bahrain. Berichte \u00fcber eine neue US-Angriffswelle im S\u00fcden des Iran, \u00d6lpreis schie\u00dft in die H\u00f6he Bessent sagt, die Stra\u00dfe von Hormus&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20521"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/20522"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}