{"id":20537,"date":"2026-09-02T10:03:13","date_gmt":"2026-09-02T08:03:13","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/alexander-von-bismarck-petition-russisches-haus-ist-eine-bruecke-zwischen-deutschland-und-russland\/"},"modified":"2026-09-02T10:03:13","modified_gmt":"2026-09-02T08:03:13","slug":"alexander-von-bismarck-petition-russisches-haus-ist-eine-bruecke-zwischen-deutschland-und-russland","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/alexander-von-bismarck-petition-russisches-haus-ist-eine-bruecke-zwischen-deutschland-und-russland\/","title":{"rendered":"Alexander von Bismarck-Petition: Russisches Haus ist eine Br\u00fccke zwischen Deutschland und Russland"},"content":{"rendered":"<div>\n<p>Das SPD-nahe <em>RedaktionsNetzwerk Deutschland<\/em> (<em>RND<\/em>) <a href=\"https:\/\/www.rnd.de\/politik\/russlands-angriffe-auf-deutschland-haben-endlich-konsequenzen-K665VXI26NHLJJJCFMJKC2346E.html\" target=\"_blank\" rel=\"noopener noreferrer\">kommentiert<\/a> die gestrigen Mitteilungen aus dem politischen Berlin, dass unter anderem dem\u00a0russischen Kulturinstitut in Berlin der Mietvertrag gek\u00fcndigt wird, mit der Schlagzeile: &#8222;Russlands Angriffe auf Deutschland haben endlich Konsequenzen&#8220;.<\/p>\n<p>Die <em>t-online<\/em>-Redaktion <a href=\"https:\/\/www.t-online.de\/nachrichten\/deutschland\/id_101415650\/nach-anschlag-in-leipzig-halle-deutschland-schliesst-russisches-haus.html\" target=\"_blank\" rel=\"noopener noreferrer\">berichtet<\/a> am Tag der verbalen Unterstellungen und Ank\u00fcndigungen, dass das Haus offiziell eine Kultureinrichtung des russischen Staates ist, jedoch &#8222;unter Sicherheitsexperten aber als Spionagezentrum gilt&#8220;.<\/p>\n<p>Alexander von Bismarck erkl\u00e4rt dazu im Rahmen seiner <a href=\"https:\/\/www.change.org\/p\/bismarck-dialog-ruft-auf-das-russisches-haus-in-berlin-zu-erhalten?recruiter=1428363542&amp;recruited_by_id=29a07100-a649-11f1-a5ad-27b6c89a053b&amp;utm_source=share_petition&amp;utm_campaign=share_petition&amp;utm_term=share_petition&amp;utm_medium=copylink&amp;share_id=gPfvzK6c2R\" target=\"_blank\" rel=\"noopener noreferrer\">ver\u00f6ffentlichten Petition<\/a> zu den eskalierenden Dynamiken im Regierungsviertel:<\/p>\n<p><em>&#8222;Gerade jetzt, wo viele Kontakte geschw\u00e4cht sind, kommt den wenigen verbliebenen Br\u00fccken des Austauschs besondere Bedeutung zu. Das Russische Haus in Berlin ist eine solche Br\u00fccke \u2013 l\u00e4ngst mehr als eine staatliche Einrichtung, fest verwurzelt im Berliner Kulturleben und sichtbares Zeichen jahrzehntelanger Beziehungen zwischen beiden L\u00e4ndern.&#8220;\u00a0<\/em><\/p>\n<p>Der sogenannte\u00a0&#8222;Bismarck Dialog&#8220; ruft daher auf,\u00a0das Russisches Haus in Berlin zu erhalten.<\/p>\n<p>Die <em>RT DE<\/em>-Redaktion zitiert auf diesem Weg den vollst\u00e4ndigen Petitionstext:<\/p>\n<p><em>Es w\u00e4re falsch und kurzsichtig, die letzten Foren des \u00f6ffentlichen und kulturellen Austauschs den aktuellen Spannungen zu opfern. Wir rufen die Bundesregierung auf, die Entscheidung zur Schlie\u00dfung zu \u00fcberdenken und r\u00fcckg\u00e4ngig zu machen. Dieser Schritt w\u00fcrde den Frieden nicht f\u00f6rdern, aber den zivilgesellschaftlichen Austausch besch\u00e4digen und die Spirale der Konfrontation weiter anheizen. Denn Kultur ist unsere letzte Chance auf Verst\u00e4ndigung und Dialog, wenn die Politik an ihre Grenzen st\u00f6\u00dft.<\/em><\/p>\n<p>Alexander von Bismarck, Gr\u00fcnder des &#8222;Bismarck-Dialogs&#8220;.<\/p>\n<p><strong>Mehr zum Thema \u2013<\/strong>\u00a0<a href=\"https:\/\/de-rtnews.com\/inland\/290376-ob-dobrindt-und-wadephul-am\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ob Dobrindt und Wadephul am Ende lachen? <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7az4l8\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das SPD-nahe RedaktionsNetzwerk Deutschland (RND) kommentiert die gestrigen Mitteilungen aus dem politischen Berlin, dass unter anderem dem\u00a0russischen Kulturinstitut in Berlin der Mietvertrag gek\u00fcndigt wird, mit der Schlagzeile: &#8222;Russlands Angriffe auf Deutschland haben endlich Konsequenzen&#8220;. Die t-online-Redaktion berichtet am Tag der verbalen Unterstellungen und Ank\u00fcndigungen, dass das Haus offiziell eine Kultureinrichtung des russischen Staates ist, jedoch [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Das SPD-nahe RedaktionsNetzwerk Deutschland (RND) kommentiert die gestrigen Mitteilungen aus dem politischen Berlin, dass unter anderem dem\u00a0russischen Kulturinstitut in Berlin der Mietvertrag gek\u00fcndigt wird, mit der Schlagzeile: &#8222;Russlands Angriffe auf Deutschland haben endlich Konsequenzen&#8220;. Die t-online-Redaktion berichtet am Tag der verbalen Unterstellungen und Ank\u00fcndigungen, dass das Haus offiziell eine Kultureinrichtung des russischen Staates ist, jedoch&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20537"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}