{"id":20677,"date":"2026-09-02T21:02:41","date_gmt":"2026-09-02T19:02:41","guid":{"rendered":"https:\/\/meiser-tv.de\/politik\/erneuter-klimaanschlag-umspannwerk-bei-koeln-angegriffen\/"},"modified":"2026-09-02T21:02:41","modified_gmt":"2026-09-02T19:02:41","slug":"erneuter-klimaanschlag-umspannwerk-bei-koeln-angegriffen","status":"publish","type":"post","link":"https:\/\/meiser-tv.de\/en\/politik\/erneuter-klimaanschlag-umspannwerk-bei-koeln-angegriffen\/","title":{"rendered":"Erneuter Klimaanschlag? Umspannwerk bei K\u00f6ln angegriffen"},"content":{"rendered":"<div>\n<p>Auch diesmal war das wahre Ziel ein Braunkohlekraftwerk \u2013 nach einem Anschlag auf ein Umspannwerk bei K\u00f6ln mussten f\u00fcnf Kraftwerksbl\u00f6cke von RWE in Bergheim und Grevenbroich vom Netz gehen. In der N\u00e4he des Braunkohlekraftwerks J\u00e4nschwalde war erst am Dienstag ein Anschlag auf ein Umspannwerk erfolgt, das den Strom aus J\u00e4nschwalde in das Netz einspeist.<\/p>\n<p>Der nordrheinwestf\u00e4lische Innenminister Herbert Reul klassifizierte den K\u00f6lner Anschlag sofort: &#8222;Es besteht der Anfangsverdacht einer verfassungsfeindlichen Sabotage&#8220;, erkl\u00e4rte er, und f\u00fcgte hinzu, es werde in zwei Richtungen ermittelt: &#8222;fremdstaatlich gelenkte Sabotage und Linksextremismus&#8220;.<\/p>\n<p>Der Kurzschluss in Bergheim wurde wohl mit einer \u00e4hnlichen Technik ausgel\u00f6st wie in Brandenburg, wo sie jedoch versagte \u2013 es wird angenommen, dass vorgefundene Pyrotechnik genutzt wurde, um einen Draht in die H\u00f6he zu schie\u00dfen, der dann einen Kurzschluss zwischen zwei Leitungen herstellte.<\/p>\n<p>In Brandenburg wird inzwischen wegen der Bildung einer terroristischen Vereinigung ermittelt. Auch gegen die Vulkangruppe, die Anfang Januar einen Anschlag auf das Berliner Stromnetz durchf\u00fchrte, wird unter diesem Verdacht ermittelt \u2013 bisher allerdings noch ohne Ergebnis.<\/p>\n<p>Braunkohlekraftwerke sind seit Jahren bevorzugte Ziele der Proteste von Klimasch\u00fctzern. Ein Beispiel daf\u00fcr war Ende Gel\u00e4nde, das sich auch gegen das Kraftwerk Niederau\u00dfem bei Bergheim wandte, das Ziel des erneuten Anschlags war. Auch J\u00e4nschwalde war 2022 Objekt von Protesten durch Ende Gel\u00e4nde. Deren Aktionen schlossen auch Blockaden, Besetzungen und Aktionen, bei denen sich Protestierende festketteten, ein. Nachdem der Kohleausstieg inzwischen politisch beschlossen ist, hat sich die Gruppe zuletzt auf Baustellen f\u00fcr Gaskraftwerke gest\u00fcrzt. Allerdings k\u00f6nnte genau diese Entwicklung dazu gef\u00fchrt haben, dass sich ein kleiner, radikaler Teil abgespalten hat, der nun zu anderen Mitteln greift.<\/p>\n<p>Dass der Innenminister von NRW au\u00dferdem die derzeit so beliebte &#8222;fremdstaatlich gelenkte Sabotage&#8220; erw\u00e4hnte, k\u00f6nnte nicht nur ein Zugest\u00e4ndnis an die politische Mode sein oder ein Versuch, dem gr\u00fcnen Koalitionspartner Ungemach zu ersparen (die gr\u00fcne Energieministerin Mona Neubaur sprach davon, bei zwei derartigen Vorf\u00e4llen handle es sich um eine &#8222;Frage der nationalen Sicherheit&#8220;). Bisher liegt f\u00fcr keinen der beiden Anschl\u00e4ge ein Bekennerschreiben vor. Die letzten Eintr\u00e4ge auf der daf\u00fcr beliebten Webseite <em>Indymedia<\/em> befassen sich mit der Verhinderung von Rechenzentren und einem Anschlag auf Heidelberger Beton. Das &#8222;Kommando Angry Birds&#8220;, das mehrfach in NRW Sabotageakte an Bahnstrecken durchf\u00fchrte, <a href=\"https:\/\/www.google.com\/url?sa=i&amp;source=web&amp;rct=j&amp;url=https:\/\/www1.wdr.de\/nrw\/linksextreme-gruppe-angry-birds-bekennt-sich-zu-bahn-sabotage-100.html&amp;ved=2ahUKEwj26LOoqNCWAxUjj4kEHapPJZgQqYcPegoIAggACAAIJhAL&amp;opi=89978449&amp;cd&amp;psig=AOvVaw1mi84vk253cloVb5aXLUz4&amp;ust=1788452884731000\" target=\"_blank\" rel=\"noopener noreferrer\">meldete<\/a> sich zuletzt Mitte Juli zur Sabotage einer Bahnstrecke bei Leverkusen. Beim Berliner Anschlag auf die Stromversorgung war das Bekennerschreiben sehr schnell ver\u00f6ffentlicht worden.<\/p>\n<p>Inzwischen meldete sich auch das LKA Baden-W\u00fcrttemberg und teilte mit, die Ermittler w\u00fcrden sich vernetzen. Dort hatte es im Juni bei Reutlingen einen Brandanschlag auf ein Umspannwerk gegeben, in dessen Folge etwa 40.000 Menschen zeitweise ohne Strom blieben.<\/p>\n<p>Der Verband kommunaler Unternehmen fordert inzwischen einen besseren Schutz kritischer Infrastruktur.\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2014\u00a0<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/de-rtnews.com\/inland\/282511-grossflaechiger-stromausfall-in-reutlingen-netzbetreiber-geht-von-brandstiftung-aus\/\">Brandstiftung? Gro\u00dffl\u00e4chiger Stromausfall in Reutlingen <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v7csu0w\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/p><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Auch diesmal war das wahre Ziel ein Braunkohlekraftwerk \u2013 nach einem Anschlag auf ein Umspannwerk bei K\u00f6ln mussten f\u00fcnf Kraftwerksbl\u00f6cke von RWE in Bergheim und Grevenbroich vom Netz gehen. In der N\u00e4he des Braunkohlekraftwerks J\u00e4nschwalde war erst am Dienstag ein Anschlag auf ein Umspannwerk erfolgt, das den Strom aus J\u00e4nschwalde in das Netz einspeist. Der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gspb_post_css":"","_uag_custom_page_level_css":"","fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-20677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"uagb_featured_image_src":{"full":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1920&fit=1920,1080&ssl=1",1920,1080,true],"thumbnail":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=150&resize=150,150&ssl=1",150,150,true],"medium":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=300&fit=300,300&ssl=1",300,300,true],"medium_large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=768&resize=768,0&ssl=1",768,0,true],"large":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1024&fit=1024,1024&ssl=1",1024,1024,true],"1536x1536":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=1536&fit=1536,1536&ssl=1",1536,1536,true],"2048x2048":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=2048&fit=2048,2048&ssl=1",2048,2048,true],"trp-custom-language-flag":["https:\/\/mleexelnfod5.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/i2.wp.com\/meiser-tv.de\/wp-content\/uploads\/2026\/05\/RSS-Hintergrund.jpg?w=18&fit=18,12&ssl=1",18,12,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/meiser-tv.de\/en\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Auch diesmal war das wahre Ziel ein Braunkohlekraftwerk \u2013 nach einem Anschlag auf ein Umspannwerk bei K\u00f6ln mussten f\u00fcnf Kraftwerksbl\u00f6cke von RWE in Bergheim und Grevenbroich vom Netz gehen. In der N\u00e4he des Braunkohlekraftwerks J\u00e4nschwalde war erst am Dienstag ein Anschlag auf ein Umspannwerk erfolgt, das den Strom aus J\u00e4nschwalde in das Netz einspeist. Der&hellip;","_links":{"self":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/comments?post=20677"}],"version-history":[{"count":0,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/posts\/20677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media\/4846"}],"wp:attachment":[{"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/media?parent=20677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/categories?post=20677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/meiser-tv.de\/en\/wp-json\/wp\/v2\/tags?post=20677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}